{"id":180917,"date":"2020-01-13T06:03:54","date_gmt":"2020-01-13T05:03:54","guid":{"rendered":"https:\/\/www.herold.at\/blog\/?p=180917"},"modified":"2023-01-16T10:44:53","modified_gmt":"2023-01-16T09:44:53","slug":"videoueberwachung-ueberwachungskamera","status":"publish","type":"post","link":"https:\/\/www.herold.at\/blog\/videoueberwachung-ueberwachungskamera\/","title":{"rendered":"Video\u00fcberwachung \u00d6sterreich: Die besten Systeme f\u00fcr Haus &#038; Wohnung"},"content":{"rendered":"\n<h1 class=\"wp-block-heading\"><strong>Video\u00fcberwachung \u00d6sterreich:<\/strong><br>Rechliche Grundlagen &amp; Anbieter<\/h1>\n\n\n\n\n\n<p>Du willst wissen wer bei dir ein- und ausgeht oder bei&nbsp;dir&nbsp;klingelt? Du willst von \u00fcberall auf der Welt die Aktivit\u00e4ten in deiner Wohnung \u00fcberwachen k\u00f6nnen?&nbsp;Du willst&nbsp;Diebe, Gauner, Einbrecher und&nbsp;Vandalen abschrecken und f\u00fcr den Fall der F\u00e4lle Beweismittel haben? Dann&nbsp;solltest du \u00fcber eine <strong>Video\u00fcberwachung<\/strong> f\u00fcr dein zu Hause nachdenken. In unserem Beitrag erf\u00e4hrst du die wesentlichsten Infos zu Video\u00fcberwachungssystemen &#8211; neben allen technischen Details au\u00dferdem auch die rechtlichen Grundlagen und welche Kosten dich erwarten.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n\n\n\n<h2 class=\"wp-block-heading\">Was bringt Video\u00fcberwachung?<\/h2>\n\n\n\n<p>Nahezu jeder von uns kennt jemanden in seinem Freundes- oder Bekanntenkreis, der k\u00fcrzlich von einem&nbsp;Einbruch betroffen war. Die Angst, in n\u00e4herer Zukunft selbst zu den Betroffenen zu z\u00e4hlen, ist daher verst\u00e4ndlicherweise gro\u00df. Obwohl Einbrecher immer organisierter und professioneller vorgehen,&nbsp;ist die Anzahl der Wohnraumeinbr\u00fcche in \u00d6sterreich&nbsp;laut&nbsp;<a href=\"https:\/\/bundeskriminalamt.at\/501\/start.aspx\">Polizeilicher Kriminalstatistik<\/a>&nbsp;in den&nbsp;vergangenen Jahren stark gesunken. W\u00e4hrend&nbsp;2009 noch 21.165 Einbr\u00fcche in \u00d6sterreich angezeigt wurden, so waren es 2018 nur noch 9.784. In den vergangenen rund 20 Jahren hat sich die Zahl der Einbr\u00fcche also mehr als halbiert. Experten&nbsp;betrachten das kontinuierlich ansteigende Alter der Bev\u00f6lkerung als den Hauptgrund f\u00fcr die seit 2014 konstant r\u00fcckl\u00e4ufige Einbruchstatistik. Ein weiterer Grund ist der steigende Wohlstand der Bev\u00f6lkerung und die damit&nbsp;einhergehend immer besser abgesicherten Wohnst\u00e4tten. Neben <a href=\"https:\/\/www.herold.at\/blog\/sicherheitstueren\/\">Sicherheitst\u00fcren<\/a> und Sicherheitsfenstern haben sich vor allem <a href=\"https:\/\/www.herold.at\/blog\/alarmanlage-kaufen-was-beachten\/\">Alarmanlagen<\/a> und <strong>Video\u00fcberwachungssysteme<\/strong> als <a href=\"https:\/\/www.herold.at\/blog\/einbruchschutz-sicheres-zuhause\/\">Einbruchschutz<\/a> bew\u00e4hrt.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Video\u00fcberwachung: Was ist zu beachten?<\/h3>\n\n\n\n<p>Wenn du deine Wohnst\u00e4tte mit einer Video\u00fcberwachung sichern m\u00f6chtest,&nbsp;solltest&nbsp;du nicht planlos irgendeine kaufen, sondern dich vorab genau informieren. Angefangen von rechtlichen Fragen (wo ist Video\u00fcberwachung erlaubt, wie lange d\u00fcrfen Daten einer Video\u00fcberwachung gespeichert werden, wie muss Video\u00fcberwachung gekennzeichnet sein) bis hin zu technischen Fragen (welche Kamera, welche Festplatte u. v. m.), gibt es beim Thema Video\u00fcberwachung einiges zu beachten.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Wann ist Video\u00fcberwachung meldepflichtig?<\/h3>\n\n\n\n<p>Seit&nbsp;Inkrafttreten der DSGVO (Datenschutzgrundverordnung) am 25. Mai 2018 geh\u00f6rt die gesetzliche Meldepflicht f\u00fcr Video\u00fcberwachung der Vergangenheit an. Stattdessen&nbsp;verlangt die DSGVO k\u00fcnftig eine sogenannte Datenschutz-Folgenabsch\u00e4tzung bei systematischer und umfangreicher Video\u00fcberwachung. Die Datenschutz-Folgeabsch\u00e4tzung&nbsp;ist eine Vorabkontrolle durch den \u00dcberwachenden selbst.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Privatgrundst\u00fcck: Wann ist eine Video\u00fcberwachung zul\u00e4ssig?<\/h3>\n\n\n\n<p>Bei einer Video\u00fcberwachung wird auf Grundrechte bez\u00fcglich Datenschutz und Privatsph\u00e4re eingegriffen. Daher gibt es aus rechtlicher Sicht einige Vorgaben zur Bildverarbeitung, die&nbsp;du unbedingt einhalten musst. Diese gesetzlichen Vorgaben sind in&nbsp;der neuen&nbsp;DSGVO und dem \u00f6sterreichischen Datenschutzgesetz festgeschrieben. Zur sogenannten Bildverarbeitung z\u00e4hlt neben der Verarbeitung von Bildern und Bewegtbildern auch die Verarbeitung von Tonaufnahmen. Folgende Vorgaben sind einzuhalten:<\/p>\n\n\n\n<ul><li>Video\u00fcberwachung ist nur dann&nbsp;zul\u00e4ssig, wenn&nbsp;ihr Einsatz&nbsp;verh\u00e4ltnism\u00e4\u00dfig ist.<\/li><li>Es muss ein berechtigtes Interesse (z. B. Schutz des Eigentums oder privates Dokumentationsinteresse) vorliegen.<\/li><li>Video\u00fcberwachung darf nur auf dem eigenen Grundst\u00fcck (Privatgrundst\u00fcck) erfolgen (Aufnahmen vom Grundst\u00fcck des Nachbarn oder \u00f6ffentlichen Pl\u00e4tzen ist ausdr\u00fccklich verboten)<\/li><\/ul>\n\n\n\n<p><strong>Fazit:&nbsp;<\/strong>Video\u00fcberwachung ist dann zul\u00e4ssig, wenn die Bildaufnahme dem vorbeugenden Schutz von Personen oder Sachen auf privaten Liegenschaften dient, die ausschlie\u00dflich vom Verantwortlichen genutzt werden. Und wenn sie r\u00e4umlich nicht \u00fcber die Liegenschaft hinaus reicht, mit Ausnahme einer zur Zweckerreichung unvermeidbaren Einbeziehung \u00f6ffentlicher Verkehrsfl\u00e4chen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Wie lange d\u00fcrfen Video\u00fcberwachungen gespeichert werden?<\/h3>\n\n\n\n<p>Aufnahmen einer Video\u00fcberwachung d\u00fcrfen prinzipiell nur f\u00fcr 72 Stunden gespeichert werden (sofern sie f\u00fcr den Zweck, f\u00fcr den sie&nbsp;aufgezeichnet wurden, nicht mehr ben\u00f6tigt werden). Wenn du einzelne Aufnahmen l\u00e4nger als 72 Stunden speichern m\u00f6chtest, musst du dies protokollieren und begr\u00fcnden.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Muss auf Video\u00fcberwachung hingewiesen werden?<\/h3>\n\n\n\n<p>Ja, wenn eine Video\u00fcberwachung existiert,&nbsp;<strong>muss darauf hingewiesen<\/strong> und diese <strong>entsprechend gekennzeichnet<\/strong> werden. Irgendwo ein Schild anzubringen reicht allerdings nicht, denn die Kennzeichnung muss so angebracht werden, dass sie gut sichtbar ist und der Betroffene die M\u00f6glichkeit hat, rechtzeitig auszuweichen.<\/p>\n\n\n\n<p><strong>Achtung<\/strong>: Wenn du die Video\u00fcberwachung nicht ordnungsgem\u00e4\u00df kennzeichnest, begehst du eine Verwaltungs\u00fcbertretung und musst mit einer <a href=\"https:\/\/www.help.gv.at\/Portal.Node\/hlpd\/public\/content\/99\/Seite.991348.html\" rel=\"nofollow\">Verwaltungsstrafe<\/a> (meistens Geldstrafen) rechnen.<\/p>\n\n\n\n<figure class=\"wp-block-image alignnone\"><a href=\"https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2019\/10\/Aussenkamera.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"830\" height=\"410\" src=\"https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2019\/10\/Aussenkamera.jpg\" alt=\"Video\u00fcberwachung\" class=\"wp-image-182195\" srcset=\"https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2019\/10\/Aussenkamera.jpg 830w, https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2019\/10\/Aussenkamera-300x148.jpg 300w, https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2019\/10\/Aussenkamera-768x379.jpg 768w\" sizes=\"(max-width: 830px) 100vw, 830px\" \/><\/a><figcaption>Video\u00fcberwachung erm\u00f6glicht schnelles Lokalisieren von Bedrohungen und sch\u00fctzt so Personen und Sachwerte. Foto: unsplash; (c) Rishabh Varshney<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Welche Video\u00fcberwachungssysteme gibt es?<\/h2>\n\n\n\n<p>Bei Vide\u00fcberwachung spricht man allgemein von Closed Circuit Television (CCTV). Auf dem Markt haben sich zwei verschiedene CCTV-\u00dcberwachungssysteme durchgesetzt. Einerseits die analoge Videotechnik und andererseits netzwerkbasierte Video\u00fcberwachung, die der analogen Videotechnik nach und nach den Rang abl\u00e4uft.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Analoge Videotechnik<\/h3>\n\n\n\n<p>Wer bei analoger Videotechnik an unscharfe Videoaufnahmen denkt, der irrt. Analoge Video\u00fcberwachung gibt es n\u00e4mlich heutzutage&nbsp;ebenfalls in High Definition (HD). Der gr\u00f6\u00dfte Pluspunkt bei analoger HD Videotechnik ist,&nbsp;dass sie leicht aufzubauen ist und sofort in Betrieb genommen werden kann.&nbsp;Die \u00dcberwachungskameras werden einfach \u00fcber Koaxialkabel mit dem Rekorder verbunden. Signalausf\u00e4lle&nbsp;sind bei den stabilen Analog-HD-\u00dcberwachungssystemen nahezu ausgeschlossen und auch die Anschaffung ist verh\u00e4ltnism\u00e4\u00dfig g\u00fcnstig.<\/p>\n\n\n\n<p><strong>Tipp<\/strong>: Wer bereits \u00fcber eine alte analoge Vide\u00fcberwachungsanlage verf\u00fcgt, kann diese auch ganz einfach und relativ g\u00fcnstig mit Full HD aufr\u00fcsten. Die alten Koaxialleitungen werden daf\u00fcr einfach \u00fcbernommen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Netzwerkbasierte \u00dcberwachung<\/h3>\n\n\n\n<p>Bei der netzwerkbasierten \u00dcberwachung komprimieren die Kameras ein Videosignal und \u00fcbertragen&nbsp;dieses \u00fcber&nbsp;ein Netzwerk auf den PC oder Netzwerkrekorder. Dort werden die Daten dann gespeichert, dekomprimiert und auf den Monitor \u00fcbertragen.&nbsp;Aufgrund der&nbsp;Komprimierung k\u00f6nnen gro\u00dfe Datenmengen&nbsp;in&nbsp;hochwertiger Aufl\u00f6sung \u00fcbertragen werden. Damit&nbsp;ist eine optimale Bildsch\u00e4rfe&nbsp;gew\u00e4hrleistet. Der gro\u00dfe Vorteil gegen\u00fcber analogen \u00dcberwachungssystemen ist, dass du beim Zugriff auf das Bildmaterial nicht auf ein spezifisches Ger\u00e4t (z. B. \u00dcberwachungsmonitor)&nbsp;angewiesen bist, sondern die&nbsp;Videodaten auch&nbsp;\u00fcber Notebooks oder Smartphones&nbsp;abrufen kannst. Netzbasierte Video\u00fcberwachung l\u00e4sst sich zudem problemlos ins <a href=\"https:\/\/www.herold.at\/blog\/smart-home\/\">Smart Home<\/a> integrieren.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Welche Kamera f\u00fcr Video\u00fcberwachung?<\/h2>\n\n\n\n<p>Um&nbsp;deine Wohnst\u00e4tte bestm\u00f6glich zu bewachen, musst du eine bzw. mehrere Kameras in deiner Wohnung postieren. Prinzipiell stehen dir drei&nbsp;g\u00e4ngige&nbsp;Varianten zur Auswahl: Bulletkameras, Netzwerkkameras sowie Dome- und Eyeballkameras. Jede Kamera hat ihr Vorz\u00fcge und Nachteile, die wir dir in den n\u00e4chsten Abs\u00e4tzen genauer vorstellen wollen.<\/p>\n\n\n\n<figure class=\"wp-block-image alignnone\"><a href=\"https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2019\/10\/Bulletkamera.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"830\" height=\"410\" src=\"https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2019\/10\/Bulletkamera.jpg\" alt=\"Bulletkamera zur Video\u00fcberwachung\" class=\"wp-image-182189\" srcset=\"https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2019\/10\/Bulletkamera.jpg 830w, https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2019\/10\/Bulletkamera-300x148.jpg 300w, https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2019\/10\/Bulletkamera-768x379.jpg 768w\" sizes=\"(max-width: 830px) 100vw, 830px\" \/><\/a><figcaption>Bulletkameras werden mittels Wandarm an einer Hausmauer oder Innenwand befestigt. Foto: Adobe Stock; (c) photographicss<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Bulletkameras&nbsp;mit Wandarm<\/h3>\n\n\n\n<p><strong>Bulletkameras&nbsp;mit Wandarm <\/strong>werden fest an&nbsp;einer Wand angebracht. Sie werden haupts\u00e4chlich als <strong>Au\u00dfenkameras<\/strong> zur \u00dcberwachung eines speziellen Grundst\u00fcckbereichs verwendet.&nbsp;Du kannst damit sowohl den Haupteingang&nbsp;als auch diverse Hintereing\u00e4nge (Terrassent\u00fcre, Fenster,&#8230;) \u00fcberwachen.&nbsp;Da ihr Geh\u00e4use&nbsp;f\u00fcr feuchte, kalte&nbsp;und hei\u00dfe&nbsp;Witterungen konzipiert ist, eignen sich Au\u00dfenkameras ideal f\u00fcr die Verwendung im Freien. Au\u00dfenkameras haben&nbsp;eine starke prophylaktische Wirkung gegen Einbrecher, weil&nbsp;sie visuell wahrgenommen werden. True-Wide-Dynamic-Range-Sensoren sorgen f\u00fcr&nbsp;hochgestochene Bilder, auch bei Gegenlicht. Eingebaute Infrarot-LEDs sorgen auch bei Dunkelheit f\u00fcr m\u00f6glichst scharfe Nachtsicht-Aufnahmen.<\/p>\n\n\n\n<p><strong>Anwendungsgebiete<\/strong>: Haupts\u00e4chlich Eingangs- und Ausgangsbereich, Zu- und Einfahrten sowie Innenh\u00f6fe<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Netzwerkkamera<\/h3>\n\n\n\n<p><strong>Netzwerkkameras<\/strong> sind f\u00fcr den Innenbereich konzipiert und liefern dort hochaufgel\u00f6ste Videoaufnahmen von bis zu&nbsp;2,0 Megapixel. Netzwerkkameras sind schwenkbar und bei Bedarf auch von Unterwegs \u00fcber das Netzwerk steuerbar. Prinzipiell sind Netzwerkkameras auch als kabellose WLAN-Version erh\u00e4ltlich, allerdings ist&nbsp;von dieser Methode&nbsp;tendenziell eher abzuraten. Professionelle Einbrecher nutzen n\u00e4mlich St\u00f6rsignale um die WLAN-\u00dcbertragung zu kappen.<\/p>\n\n\n\n<p><strong>Anwendungsgebiete<\/strong>: Wohnr\u00e4ume, Vorzimmer und Garagen<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Domekamera &amp; Eyeballkamera<\/h3>\n\n\n\n<p>Bei <strong>Domekameras<\/strong> handelt es sich um robuste All-In-One-\u00dcberwachungskameras. Ihr robustes Geh\u00e4use sch\u00fctzt sie vor Vandalismus und mutwilligen Besch\u00e4digungen.&nbsp;Domekameras sind sowohl als Netzwerkkamera als auch analog und digital erh\u00e4ltlich. Spezielle Au\u00dfen-Domekameras eignen sich&nbsp;zudem f\u00fcr den Einsatz im Freien.&nbsp;Mit besonderen&nbsp;Panorama-Domekameras,&nbsp;ist sogar&nbsp;eine \u00dcberwachung von bis zu 320\u00b0 m\u00f6glich. Eng mit der Domekamera verwandt ist die Eyballkamera. Sie ist allerdings deutlich weniger robust. Beide Kameras sind in sehr kleinen Bauformen erh\u00e4ltlich,&nbsp;die&nbsp;f\u00fcr m\u00f6glichst unauff\u00e4llige \u00dcberwachung sorgen.<\/p>\n\n\n\n<p><strong>Anwendungsbereich<\/strong>: Ideal f\u00fcr&nbsp;Zimmerdecken, aber prinzipiell universell einsetzbar<\/p>\n\n\n\n<figure class=\"wp-block-image alignnone\"><a href=\"https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2019\/10\/Domekamera.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"830\" height=\"410\" src=\"https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2019\/10\/Domekamera.jpg\" alt=\"Domekamera zur Video\u00fcberwachung\" class=\"wp-image-182183\" srcset=\"https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2019\/10\/Domekamera.jpg 830w, https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2019\/10\/Domekamera-300x148.jpg 300w, https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2019\/10\/Domekamera-768x379.jpg 768w\" sizes=\"(max-width: 830px) 100vw, 830px\" \/><\/a><figcaption>Domekameras sind sehr robust und bruchsicher. Foto: Adobe Stock; (c) missisya<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Was kostet eine Video\u00fcberwachungsanlage?<\/h2>\n\n\n\n<p>Die Preisspanne einer Video\u00fcberwachungsanlage ist gro\u00df. Sie reicht von rund&nbsp;<strong>\u20ac 2.000<\/strong><strong>&nbsp;bis \u20ac 9.000 <\/strong>(jeweils inkl. Einbau und Installation). Das obere Preissegment wird erreicht, wenn du viele Kameras ben\u00f6tigst (gro\u00dfes und\/oder verwinkeltes Geb\u00e4ude) und zus\u00e4tzlich auf bestm\u00f6gliche Qualit\u00e4t und Aufl\u00f6sung setzen m\u00f6chtest. Zus\u00e4tzliche Features wie <strong>Videoteiler<\/strong> (\u00dcbertragung des Signals auf mehrere Monitore an unterschiedlicher Position) oder <strong>W\u00e4rmebildkameras<\/strong>&nbsp;schlagen sich ebenfalls im Preis nieder. Durchschnittlich muss man f\u00fcr ein Einfamilienhaus aber mit einem Gesamtpreis von rund <strong>\u20ac 4.000<\/strong> rechnen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Die besten Anbieter f\u00fcr Video\u00fcberwachungsanlagen und andere Sicherheitssysteme<\/h3>\n\n\n\n<h4 class=\"wp-block-heading\">ZEUS Sicherheitstechnik \u2605\u2605\u2605\u2605\u2605 (4,8 bei 207 Bewertungen)<\/h4>\n\n\n\n<p>Die Firma <strong>ZEUS Sicherheitstechnik<\/strong> ist die mit Abstand am besten bewertete Firma f\u00fcr Alaramanlagen- und Sicherheitstechnik auf herold.at. Bei ZEUS erh\u00e4ltst du Alarmanlagen, Brandmeldeanlagen und nat\u00fcrlich auch Video\u00fcberwachungsanlagen. Mit <a href=\"https:\/\/www.herold.at\/gelbe-seiten\/was_zeus\/\" rel=\"nofollow\">7 Standorten<\/a> in ganz \u00d6sterreich, findest du mit gro\u00dfer Wahrscheinlichkeit auch einen Standort in deiner N\u00e4he, wo du dich ausf\u00fchrlich zur Video\u00fcberwachung beraten lassen kannst.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.herold.at\/gelbe-seiten\/wien\/bCCMm\/zeus-sicherheitstechnik\/\"><strong>ZEUS Sicherheitstechnik<\/strong><\/a>, <a href=\"https:\/\/www.herold.at\/gelbe-seiten\/wien\/bCCMm\/zeus-sicherheitstechnik\/\">1200 Wien<\/a>, <a href=\"https:\/\/www.herold.at\/gelbe-seiten\/graz\/3KdjW\/zeus-sicherheitstechnik\/\" rel=\"nofollow\">8010 Graz<\/a>,&nbsp;<a href=\"https:\/\/www.herold.at\/gelbe-seiten\/puchenau\/tWNqw\/zeus-sicherheitstechnik\/\" rel=\"nofollow\">4048 Puchenau<\/a><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">ProfiAlarm&nbsp;\u2605\u2605\u2605\u2605\u2605 (5,0 bei&nbsp;173 Bewertungen)<\/h4>\n\n\n\n<p>Bei <strong>ProfiAlarm<\/strong> bist du im wahrsten Sinne des Wortes stets auf der sicheren Seite. ProfiAlarm bietet neben Video\u00fcberwachungsanlagen au\u00dferdem Alarmanlagen, Sicherheitst\u00fcren und hochwertige Tresore an. Seinen Firmensitz hat das Unternehmen in Brunn am Gebirge.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.herold.at\/gelbe-seiten\/brunn-am-gebirge\/8SMtQ\/profialarm-eu\/\">ProfiAlarm , 2345 Brunn am Gebirge<\/a><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Haus der Schl\u00f6sser&nbsp;\u2605\u2605\u2605\u2605\u2605 (4,9 bei&nbsp;128 Bewertungen)<\/h4>\n\n\n\n<p>Das <strong>Haus der Schl\u00f6sser<\/strong> ist eigentlich ein Schl\u00fcsseldienst, der sich auf Zutrittskontrolle und Sicherheitst\u00fcren spezialisiert hat. Aber auch Video\u00fcberwachung z\u00e4hlt seit geraumer Zeit zum Portfolio des Unternehmens. Beim Haus der Schl\u00f6sser kannst du dir deine Video\u00fcberwachung sogar mit einer elektrischen Zutrittskontrolle kombinieren lassen.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.herold.at\/gelbe-seiten\/linz\/NfTbX\/haus-der-schl%C3%B6sser\/?hdg=INET_54_Alarmanlage+u+Sicherheitssystem\"><strong>HAUS der SCHL\u00d6SSER<\/strong><\/a>, 4020 Linz<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Safety First Alarmsysteme \u2605\u2605\u2605\u2605\u2605 (5,0 bei&nbsp;77 Bewertungen)<\/h4>\n\n\n\n<p>Der am besten bewertete Spezialist f\u00fcr elektronische Alarmsysteme in K\u00e4rnten ist die Firma <strong>Safety First Alarmsysteme<\/strong> in Wolfsberg. Alarmanlagen, Gegensprechanlagen und Video\u00fcberwachung wird dort angeboten.<\/p>\n\n\n\n<p><strong><a href=\"https:\/\/www.herold.at\/gelbe-seiten\/wolfsberg\/D41qz\/safety-first-alarmsysteme-gmbh\/\">Safety First Alarmsysteme<\/a><\/strong>, 9400 Wolfsberg<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">SEKURUM&nbsp;<strong>\u2605\u2605\u2605\u2605\u2605 <\/strong>(4,9 bei&nbsp;38 Bewertungen)<\/h4>\n\n\n\n<p>Um Sicherheitstechnik in jeglicher Hinsicht geht es bei der Firma <strong>SEKURUM<\/strong>. Speziell gesicherte Schl\u00f6sser, Schlie\u00dfanlagen, Schl\u00fcssel, Safes, Briefk\u00e4sten, Alarmanlagen und eben auch Video\u00fcberwachungen sind&nbsp;beim am besten bewerteten Sicherheitsunternehmen Innsbrucks&nbsp;erh\u00e4ltlich.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.herold.at\/gelbe-seiten\/innsbruck\/tNhv3\/sekurum-gmbh\/?hdg=INET_54_Alarmanlage+u+Sicherheitssystem\"><strong>SEKURUM<\/strong><\/a>, 6020 Innsbruck<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Pichler Sicherheits- und Systemtechnik&nbsp;<strong>\u2605\u2605\u2605\u2605\u2605&nbsp;<\/strong>(4,9&nbsp;bei&nbsp;16 Bewertungen)<\/h4>\n\n\n\n<p>Auch Salzburg verf\u00fcgt \u00fcber ein sehr gut bewertetes Unternehmen auf herold.at. Bei <strong>Pichler<\/strong> erh\u00e4ltst du T\u00fcr- und Fenstersicherungen, Brandmeldeanlagen, Alarmanlagen, Tresore, Gegensprechanlagen und Video\u00fcberwachungssysteme. In \u00d6sterreich setzt unter anderem das Technische Museum in Wien auf Sicherheitstechnik von Pichler.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.herold.at\/gelbe-seiten\/salzburg\/shbzM\/pichler-sicherheits--und-systemtechnik-gesmbh-co-kg\/\" rel=\"nofollow\"><strong>Pichler Sicherheits- und Systemtechnik<\/strong><\/a>, 5020 Salzburg<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column blog_sidebar is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<div class=\"wp-block-columns is-layout-flex wp-container-5 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:15%\"><div class=\"shariff shariff-align-flex-start shariff-widget-align-flex-start\"><ul class=\"shariff-buttons theme-round orientation-horizontal buttonsize-medium\"><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.herold.at%2Fblog%2Fvideoueberwachung-ueberwachungskamera%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button twitter shariff-nocustomcolor\" style=\"background-color:#32bbf5\"><a href=\"https:\/\/twitter.com\/share?url=https%3A%2F%2Fwww.herold.at%2Fblog%2Fvideoueberwachung-ueberwachungskamera%2F&text=Video%C3%BCberwachung%20%C3%96sterreich%3A%20Die%20besten%20Systeme%20f%C3%BCr%20Haus%20%26%20Wohnung\" title=\"Bei Twitter teilen\" aria-label=\"Bei Twitter teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#55acee; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 30 32\"><path fill=\"#55acee\" d=\"M29.7 6.8q-1.2 1.8-3 3.1 0 0.3 0 0.8 0 2.5-0.7 4.9t-2.2 4.7-3.5 4-4.9 2.8-6.1 1q-5.1 0-9.3-2.7 0.6 0.1 1.5 0.1 4.3 0 7.6-2.6-2-0.1-3.5-1.2t-2.2-3q0.6 0.1 1.1 0.1 0.8 0 1.6-0.2-2.1-0.4-3.5-2.1t-1.4-3.9v-0.1q1.3 0.7 2.8 0.8-1.2-0.8-2-2.2t-0.7-2.9q0-1.7 0.8-3.1 2.3 2.8 5.5 4.5t7 1.9q-0.2-0.7-0.2-1.4 0-2.5 1.8-4.3t4.3-1.8q2.7 0 4.5 1.9 2.1-0.4 3.9-1.5-0.7 2.2-2.7 3.4 1.8-0.2 3.5-0.9z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fwww.herold.at%2Fblog%2Fvideoueberwachung-ueberwachungskamera%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0077b5; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button xing shariff-nocustomcolor\" style=\"background-color:#29888a\"><a href=\"https:\/\/www.xing.com\/spi\/shares\/new?url=https%3A%2F%2Fwww.herold.at%2Fblog%2Fvideoueberwachung-ueberwachungskamera%2F\" title=\"Bei XING teilen\" aria-label=\"Bei XING teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#126567; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 25 32\"><path fill=\"#126567\" d=\"M10.7 11.9q-0.2 0.3-4.6 8.2-0.5 0.8-1.2 0.8h-4.3q-0.4 0-0.5-0.3t0-0.6l4.5-8q0 0 0 0l-2.9-5q-0.2-0.4 0-0.7 0.2-0.3 0.5-0.3h4.3q0.7 0 1.2 0.8zM25.1 0.4q0.2 0.3 0 0.7l-9.4 16.7 6 11q0.2 0.4 0 0.6-0.2 0.3-0.6 0.3h-4.3q-0.7 0-1.2-0.8l-6-11.1q0.3-0.6 9.5-16.8 0.4-0.8 1.2-0.8h4.3q0.4 0 0.5 0.3z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button mailto shariff-nocustomcolor\" style=\"background-color:#a8a8a8\"><a href=\"mailto:?body=https%3A%2F%2Fwww.herold.at%2Fblog%2Fvideoueberwachung-ueberwachungskamera%2F&subject=Video%C3%BCberwachung%20%C3%96sterreich%3A%20Die%20besten%20Systeme%20f%C3%BCr%20Haus%20%26%20Wohnung\" title=\"Per E-Mail versenden\" aria-label=\"Per E-Mail versenden\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#999; color:#fff\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#999\" d=\"M32 12.7v14.2q0 1.2-0.8 2t-2 0.9h-26.3q-1.2 0-2-0.9t-0.8-2v-14.2q0.8 0.9 1.8 1.6 6.5 4.4 8.9 6.1 1 0.8 1.6 1.2t1.7 0.9 2 0.4h0.1q0.9 0 2-0.4t1.7-0.9 1.6-1.2q3-2.2 8.9-6.1 1-0.7 1.8-1.6zM32 7.4q0 1.4-0.9 2.7t-2.2 2.2q-6.7 4.7-8.4 5.8-0.2 0.1-0.7 0.5t-1 0.7-0.9 0.6-1.1 0.5-0.9 0.2h-0.1q-0.4 0-0.9-0.2t-1.1-0.5-0.9-0.6-1-0.7-0.7-0.5q-1.6-1.1-4.7-3.2t-3.6-2.6q-1.1-0.7-2.1-2t-1-2.5q0-1.4 0.7-2.3t2.1-0.9h26.3q1.2 0 2 0.8t0.9 2z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button sms shariff-nocustomcolor shariff-mobile\" style=\"background-color:#d7d9d8\"><a href=\"sms:?&body=https%3A%2F%2Fwww.herold.at%2Fblog%2Fvideoueberwachung-ueberwachungskamera%2F\" title=\"Per SMS teilen\" aria-label=\"Per SMS teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#a1e877; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"510\" height=\"510\" viewBox=\"0 0 510 510\"><path fill=\"#a1e877\" d=\"M459 0H51C23 0 0 23 0 51v459l102-102h357c28.1 0 51-22.9 51-51V51C510 23 487.1 0 459 0zM178.5 229.5h-51v-51h51V229.5zM280.5 229.5h-51v-51h51V229.5zM382.5 229.5h-51v-51h51V229.5z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button whatsapp shariff-nocustomcolor\" style=\"background-color:#5cbe4a\"><a href=\"https:\/\/api.whatsapp.com\/send?text=https%3A%2F%2Fwww.herold.at%2Fblog%2Fvideoueberwachung-ueberwachungskamera%2F%20Video%C3%BCberwachung%20%C3%96sterreich%3A%20Die%20besten%20Systeme%20f%C3%BCr%20Haus%20%26%20Wohnung\" title=\"Bei Whatsapp teilen\" aria-label=\"Bei Whatsapp teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#34af23; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#34af23\" d=\"M17.6 17.4q0.2 0 1.7 0.8t1.6 0.9q0 0.1 0 0.3 0 0.6-0.3 1.4-0.3 0.7-1.3 1.2t-1.8 0.5q-1 0-3.4-1.1-1.7-0.8-3-2.1t-2.6-3.3q-1.3-1.9-1.3-3.5v-0.1q0.1-1.6 1.3-2.8 0.4-0.4 0.9-0.4 0.1 0 0.3 0t0.3 0q0.3 0 0.5 0.1t0.3 0.5q0.1 0.4 0.6 1.6t0.4 1.3q0 0.4-0.6 1t-0.6 0.8q0 0.1 0.1 0.3 0.6 1.3 1.8 2.4 1 0.9 2.7 1.8 0.2 0.1 0.4 0.1 0.3 0 1-0.9t0.9-0.9zM14 26.9q2.3 0 4.3-0.9t3.6-2.4 2.4-3.6 0.9-4.3-0.9-4.3-2.4-3.6-3.6-2.4-4.3-0.9-4.3 0.9-3.6 2.4-2.4 3.6-0.9 4.3q0 3.6 2.1 6.6l-1.4 4.2 4.3-1.4q2.8 1.9 6.2 1.9zM14 2.2q2.7 0 5.2 1.1t4.3 2.9 2.9 4.3 1.1 5.2-1.1 5.2-2.9 4.3-4.3 2.9-5.2 1.1q-3.5 0-6.5-1.7l-7.4 2.4 2.4-7.2q-1.9-3.2-1.9-6.9 0-2.7 1.1-5.2t2.9-4.3 4.3-2.9 5.2-1.1z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:85%\">\n\n<div id=\"content-right_column_post-block_60cc4d9c2f5b9\" class=\"flex_wrapper right_column_post \">\n <div class=\"right_author_infos shadow\" itemscope itemtype=\"https:\/\/schema.org\/Person\">\n <div class=\"blurred_header_img_wrapper\">\n <img decoding=\"async\" class=\"blurred_header_img\" src=\"\" alt=\"\" title=\"\">\n <\/div>\n \n <img decoding=\"async\" class=\"author_profile_img\" src=\"\" alt=\"\" title=\"\" itemprop=\"image\">\n <p class=\"right_author_name\" itemprop=\"name\"><\/p>\n <meta itemprop=\"jobTitle\" content=\"\">\n\n <p class=\"right_author_role\"><\/p>\n <\/div>\n \n <style>\n .ew__iframe{\n aspect-ratio:212 \/ 177}\n .iframe__container{\n position:relative;\n}\n .iframe__container a{\n position:absolute !important;\n width:100% !important;\n height:100% !important;\n padding:0 !important;\n left:0;\n top:0;\n z-index:15;\n border:0!important\n}\n .iframe__container iframe{\n overflow:hidden;\n border-radius:30px;\n}\n @media (max-width:1024px){\n .iframe__container iframe{\n width:100%!important;\n}\n}\n <\/style>\n <div class=\"iframe__container\">\n <a href=\"https:\/\/www.herold.at\/marketing\/onlinecomplete\/herold-sichtbarkeits-check?utm_source=herold_b2c_blog&#038;utm_campaign=b2c_blog_sidebar&#038;utm_content=handy_check_statisch&#038;utm_medium=videoueberwachung-ueberwachungskamera\" target=\"_blank\"><\/a> \n <iframe loading=\"lazy\" class=\"ew__iframe\" src=\"https:\/\/www.herold.at\/blog\/wp-content\/themes\/heroldblog\/banner_ads\/Statsich_HTML5\/index.html\" frameborder=\"0\" height=\"100%\" width=\"100%\"><\/iframe>\n <\/div>\n <\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<article id=\"teaser-block_60cc5e652f5bb\" class=\"teaser_wrapper themen_teaser_wrapper flex_wrapper related \">\n \n \n <div class=\"\">\n <div class=\"shadow \" itemscope itemtype=\"https:\/\/schema.org\/Article\">\n <div class=\"sh_inner\">\n \n \n <a href=\"https:\/\/www.herold.at\/blog\/kategorie\/bauen-wohnen\/haustechnik-und-oekologie\/\"><span class=\"ad_span\">Haustechnik &amp; \u00d6kologie<\/span> <\/a>\n <a href=\"https:\/\/www.herold.at\/blog\/alarmanlage-kaufen-was-beachten\/\">\n <img loading=\"lazy\" width=\"400\" height=\"265\" src=\"https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2019\/10\/Alarmanlage-Wien-400x265.jpeg\" class=\"attachment-blurred_header size-blurred_header wp-post-image\" alt=\"Alarmanlage\" decoding=\"async\" srcset=\"https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2019\/10\/Alarmanlage-Wien-400x265.jpeg 400w, https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2019\/10\/Alarmanlage-Wien-250x166.jpeg 250w, https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2019\/10\/Alarmanlage-Wien-700x464.jpeg 700w, https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2019\/10\/Alarmanlage-Wien-768x509.jpeg 768w, https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2019\/10\/Alarmanlage-Wien-1536x1018.jpeg 1536w, https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2019\/10\/Alarmanlage-Wien-2048x1357.jpeg 2048w, https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2019\/10\/Alarmanlage-Wien-1920x1272.jpeg 1920w, https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2019\/10\/Alarmanlage-Wien-1000x663.jpeg 1000w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/> <\/a>\n <div class=\"shadow_inner\">\n <p class=\"right_author_name\">Alarmanlagen Wien: top Beratung f\u00fcr mehr Sicherheit!<\/p>\n \n \n \n <p class=\"author_readtime\" itemprop=\"name\">Herold Redaktion | 11 Min.<\/p>\n\n <a href=\"https:\/\/www.herold.at\/blog\/alarmanlage-kaufen-was-beachten\/\" class=\"cta_btn blue\">Zum Beitrag<\/a>\n <\/div>\n <\/div>\n <\/div> \n <div class=\"shadow \" itemscope itemtype=\"https:\/\/schema.org\/Article\">\n <div class=\"sh_inner\">\n \n \n <a href=\"https:\/\/www.herold.at\/blog\/kategorie\/bauen-wohnen\/haustechnik-und-oekologie\/\"><span class=\"ad_span\">Haustechnik &amp; \u00d6kologie<\/span> <\/a>\n <a href=\"https:\/\/www.herold.at\/blog\/einbruchschutz-sicheres-zuhause\/\">\n <img loading=\"lazy\" width=\"400\" height=\"267\" src=\"https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2018\/09\/Einbruchschutz-187299220-400x267.jpg\" class=\"attachment-blurred_header size-blurred_header wp-post-image\" alt=\"Einbruchschutz\" decoding=\"async\" srcset=\"https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2018\/09\/Einbruchschutz-187299220-400x267.jpg 400w, https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2018\/09\/Einbruchschutz-187299220-250x167.jpg 250w, https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2018\/09\/Einbruchschutz-187299220-700x466.jpg 700w, https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2018\/09\/Einbruchschutz-187299220-768x512.jpg 768w, https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2018\/09\/Einbruchschutz-187299220-750x500.jpg 750w, https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2018\/09\/Einbruchschutz-187299220-300x200.jpg 300w, https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2018\/09\/Einbruchschutz-187299220.jpg 830w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/> <\/a>\n <div class=\"shadow_inner\">\n <p class=\"right_author_name\">Einbruchschutz: So machst du dein Zuhause sicher<\/p>\n \n \n \n <p class=\"author_readtime\" itemprop=\"name\">Herold Redaktion | 9 Min.<\/p>\n\n <a href=\"https:\/\/www.herold.at\/blog\/einbruchschutz-sicheres-zuhause\/\" class=\"cta_btn blue\">Zum Beitrag<\/a>\n <\/div>\n <\/div>\n <\/div> \n <div class=\"shadow \" itemscope itemtype=\"https:\/\/schema.org\/Article\">\n <div class=\"sh_inner\">\n \n \n <a href=\"https:\/\/www.herold.at\/blog\/kategorie\/bauen-wohnen\/innenausbau\/\"><span class=\"ad_span\">Innenausbau<\/span> <\/a>\n <a href=\"https:\/\/www.herold.at\/blog\/schallschutzfenster-klasse-kosten\/\">\n <img loading=\"lazy\" width=\"400\" height=\"247\" src=\"https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2018\/06\/Schallschutzfenster_192573903-400x247.jpg\" class=\"attachment-blurred_header size-blurred_header wp-post-image\" alt=\"junge barf\u00fc\u00dfige Frau mit Dutt genie\u00dft Ausblick vor einem Schallschutzfenster\" decoding=\"async\" srcset=\"https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2018\/06\/Schallschutzfenster_192573903-400x247.jpg 400w, https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2018\/06\/Schallschutzfenster_192573903-250x154.jpg 250w, https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2018\/06\/Schallschutzfenster_192573903-700x432.jpg 700w, https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2018\/06\/Schallschutzfenster_192573903-768x474.jpg 768w, https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2018\/06\/Schallschutzfenster_192573903-1536x947.jpg 1536w, https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2018\/06\/Schallschutzfenster_192573903-2048x1263.jpg 2048w, https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2018\/06\/Schallschutzfenster_192573903-1920x1184.jpg 1920w, https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2018\/06\/Schallschutzfenster_192573903-1000x617.jpg 1000w, https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2018\/06\/Schallschutzfenster_192573903-300x185.jpg 300w, https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2018\/06\/Schallschutzfenster_192573903-1024x632.jpg 1024w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/> <\/a>\n <div class=\"shadow_inner\">\n <p class=\"right_author_name\">Schallschutzfenster: Hilfe gegen Stra\u00dfenl\u00e4rm<\/p>\n \n \n \n <p class=\"author_readtime\" itemprop=\"name\">Dominik Knapp | 6 Min.<\/p>\n\n <a href=\"https:\/\/www.herold.at\/blog\/schallschutzfenster-klasse-kosten\/\" class=\"cta_btn blue\">Zum Beitrag<\/a>\n <\/div>\n <\/div>\n <\/div> \n <\/div> \n \n \n<\/article>","protected":false},"excerpt":{"rendered":"<p>Video\u00fcberwachung \u00d6sterreich:Rechliche Grundlagen &amp; Anbieter Du willst wissen wer bei dir ein- und ausgeht oder bei&nbsp;dir&nbsp;klingelt? Du willst von \u00fcberall auf der Welt die Aktivit\u00e4ten in deiner Wohnung \u00fcberwachen k\u00f6nnen?&nbsp;Du willst&nbsp;Diebe, Gauner, Einbrecher und&nbsp;Vandalen abschrecken und f\u00fcr den Fall der F\u00e4lle Beweismittel haben? Dann&nbsp;solltest du \u00fcber eine Video\u00fcberwachung f\u00fcr dein zu Hause nachdenken. In unserem Beitrag erf\u00e4hrst du die wesentlichsten Infos zu Video\u00fcberwachungssystemen &#8211; neben allen technischen Details au\u00dferdem auch die rechtlichen Grundlagen und welche Kosten dich erwarten. Was bringt Video\u00fcberwachung? Nahezu jeder von uns kennt jemanden in seinem Freundes- oder Bekanntenkreis, der k\u00fcrzlich von einem&nbsp;Einbruch betroffen war. Die Angst, in n\u00e4herer Zukunft selbst zu den Betroffenen zu z\u00e4hlen, ist daher verst\u00e4ndlicherweise gro\u00df. Obwohl Einbrecher immer organisierter und professioneller vorgehen,&nbsp;ist die Anzahl der Wohnraumeinbr\u00fcche in \u00d6sterreich&nbsp;laut&nbsp;Polizeilicher Kriminalstatistik&nbsp;in den&nbsp;vergangenen Jahren stark gesunken. W\u00e4hrend&nbsp;2009 noch 21.165 Einbr\u00fcche in \u00d6sterreich angezeigt wurden, so waren es 2018 nur noch 9.784. In den vergangenen rund 20 Jahren hat sich die Zahl der Einbr\u00fcche also mehr als halbiert. Experten&nbsp;betrachten das kontinuierlich ansteigende Alter der Bev\u00f6lkerung als den Hauptgrund f\u00fcr die seit 2014 konstant r\u00fcckl\u00e4ufige Einbruchstatistik. Ein weiterer Grund ist der steigende Wohlstand der Bev\u00f6lkerung und die damit&nbsp;einhergehend immer besser abgesicherten Wohnst\u00e4tten. Neben Sicherheitst\u00fcren und Sicherheitsfenstern haben sich vor allem Alarmanlagen und Video\u00fcberwachungssysteme als Einbruchschutz bew\u00e4hrt. Video\u00fcberwachung: Was ist zu beachten? Wenn du deine Wohnst\u00e4tte mit einer Video\u00fcberwachung sichern m\u00f6chtest,&nbsp;solltest&nbsp;du nicht planlos irgendeine kaufen, sondern dich vorab genau informieren. Angefangen von rechtlichen Fragen (wo ist Video\u00fcberwachung erlaubt, wie lange d\u00fcrfen Daten einer Video\u00fcberwachung gespeichert werden, wie muss Video\u00fcberwachung gekennzeichnet sein) bis hin zu technischen Fragen (welche Kamera, welche Festplatte u. v. m.), gibt es beim Thema Video\u00fcberwachung einiges zu beachten. Wann ist Video\u00fcberwachung meldepflichtig? Seit&nbsp;Inkrafttreten der DSGVO (Datenschutzgrundverordnung) am 25. Mai 2018 geh\u00f6rt die gesetzliche Meldepflicht f\u00fcr Video\u00fcberwachung der Vergangenheit an. Stattdessen&nbsp;verlangt die DSGVO k\u00fcnftig eine sogenannte Datenschutz-Folgenabsch\u00e4tzung bei systematischer und umfangreicher Video\u00fcberwachung. Die Datenschutz-Folgeabsch\u00e4tzung&nbsp;ist eine Vorabkontrolle durch den \u00dcberwachenden selbst. Privatgrundst\u00fcck: Wann ist eine Video\u00fcberwachung zul\u00e4ssig? Bei einer Video\u00fcberwachung wird auf Grundrechte bez\u00fcglich Datenschutz und Privatsph\u00e4re eingegriffen. Daher gibt es aus rechtlicher Sicht einige Vorgaben zur Bildverarbeitung, die&nbsp;du unbedingt einhalten musst. Diese gesetzlichen Vorgaben sind in&nbsp;der neuen&nbsp;DSGVO und dem \u00f6sterreichischen Datenschutzgesetz festgeschrieben. Zur sogenannten Bildverarbeitung z\u00e4hlt neben der Verarbeitung von Bildern und Bewegtbildern auch die Verarbeitung von Tonaufnahmen. Folgende Vorgaben sind einzuhalten: Video\u00fcberwachung ist nur dann&nbsp;zul\u00e4ssig, wenn&nbsp;ihr Einsatz&nbsp;verh\u00e4ltnism\u00e4\u00dfig ist. Es muss ein berechtigtes Interesse (z. B. Schutz des Eigentums oder privates Dokumentationsinteresse) vorliegen. Video\u00fcberwachung darf nur auf dem eigenen Grundst\u00fcck (Privatgrundst\u00fcck) erfolgen (Aufnahmen vom Grundst\u00fcck des Nachbarn oder \u00f6ffentlichen Pl\u00e4tzen ist ausdr\u00fccklich verboten) Fazit:&nbsp;Video\u00fcberwachung ist dann zul\u00e4ssig, wenn die Bildaufnahme dem vorbeugenden Schutz von Personen oder Sachen auf privaten Liegenschaften dient, die ausschlie\u00dflich vom Verantwortlichen genutzt werden. Und wenn sie r\u00e4umlich nicht \u00fcber die Liegenschaft hinaus reicht, mit Ausnahme einer zur Zweckerreichung unvermeidbaren Einbeziehung \u00f6ffentlicher Verkehrsfl\u00e4chen. Wie lange d\u00fcrfen Video\u00fcberwachungen gespeichert werden? Aufnahmen einer Video\u00fcberwachung d\u00fcrfen prinzipiell nur f\u00fcr 72 Stunden gespeichert werden (sofern sie f\u00fcr den Zweck, f\u00fcr den sie&nbsp;aufgezeichnet wurden, nicht mehr ben\u00f6tigt werden). Wenn du einzelne Aufnahmen l\u00e4nger als 72 Stunden speichern m\u00f6chtest, [&hellip;]<\/p>\n","protected":false},"author":57,"featured_media":182162,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[11799],"tags":[],"acf":[],"yoast_head":"\n<title>Video\u00fcberwachung | Rechtliche und technische Infos - HEROLD<\/title>\n<meta name=\"description\" content=\"Erfahre, wo Video\u00fcberwachung erlaubt ist, wie lange die Daten gespeichert werden d\u00fcrfen, wie du eine \u00dcberwachungskamera kennzeichnen musst &amp; vieles mehr.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.herold.at\/blog\/videoueberwachung-ueberwachungskamera\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Video\u00fcberwachung: Was sie kostet und was erlaubt ist\" \/>\n<meta property=\"og:description\" content=\"Erfahre, wo Video\u00fcberwachung erlaubt ist, wie lange die Daten gespeichert werden d\u00fcrfen, wie du eine \u00dcberwachungskamera kennzeichnen musst &amp; vieles mehr.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.herold.at\/blog\/videoueberwachung-ueberwachungskamera\/\" \/>\n<meta property=\"og:site_name\" content=\"Herold Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/derherold\" \/>\n<meta property=\"article:author\" content=\"#\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-13T05:03:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-16T09:44:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2019\/10\/Ueberwachungskamera.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"830\" \/>\n\t<meta property=\"og:image:height\" content=\"553\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dominik Knapp\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dominik Knapp\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.herold.at\/blog\/videoueberwachung-ueberwachungskamera\/\",\"url\":\"https:\/\/www.herold.at\/blog\/videoueberwachung-ueberwachungskamera\/\",\"name\":\"Video\u00fcberwachung | Rechtliche und technische Infos - HEROLD\",\"isPartOf\":{\"@id\":\"https:\/\/www.herold.at\/blog\/#website\"},\"datePublished\":\"2020-01-13T05:03:54+00:00\",\"dateModified\":\"2023-01-16T09:44:53+00:00\",\"author\":{\"@id\":\"https:\/\/www.herold.at\/blog\/#\/schema\/person\/76f600ea6ba66f9ce2c49741903c213d\"},\"description\":\"Erfahre, wo Video\u00fcberwachung erlaubt ist, wie lange die Daten gespeichert werden d\u00fcrfen, wie du eine \u00dcberwachungskamera kennzeichnen musst & vieles mehr.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.herold.at\/blog\/videoueberwachung-ueberwachungskamera\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.herold.at\/blog\/videoueberwachung-ueberwachungskamera\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.herold.at\/blog\/videoueberwachung-ueberwachungskamera\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.herold.at\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Video\u00fcberwachung \u00d6sterreich: Die besten Systeme f\u00fcr Haus &#038; Wohnung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.herold.at\/blog\/#website\",\"url\":\"https:\/\/www.herold.at\/blog\/\",\"name\":\"Herold Blog\",\"description\":\"Ratgeber &amp; Blog von herold.at\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.herold.at\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.herold.at\/blog\/#\/schema\/person\/76f600ea6ba66f9ce2c49741903c213d\",\"name\":\"Dominik Knapp\",\"description\":\"SEO Text Guru Dominik Knapp ist SEO-Experte und Content Creator mit einem Faible f\u00fcr Sport, Star Wars und den Eurovision Song Contest. Er besch\u00e4ftigt sich seit 2013 mit Suchmaschinenoptimierung, Google Rankings und internen Verlinkungen. Zuvor war er mehrere Jahre als Sportjournalist t\u00e4tig.\",\"sameAs\":[\"http:\/\/www.herold.at\",\"#\",\"https:\/\/twitter.com\/#\"],\"url\":\"https:\/\/www.herold.at\/blog\/author\/dominik-knapp\/\"}]}<\/script>\n","yoast_head_json":{"title":"Video\u00fcberwachung | Rechtliche und technische Infos - HEROLD","description":"Erfahre, wo Video\u00fcberwachung erlaubt ist, wie lange die Daten gespeichert werden d\u00fcrfen, wie du eine \u00dcberwachungskamera kennzeichnen musst & vieles mehr.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.herold.at\/blog\/videoueberwachung-ueberwachungskamera\/","og_locale":"de_DE","og_type":"article","og_title":"Video\u00fcberwachung: Was sie kostet und was erlaubt ist","og_description":"Erfahre, wo Video\u00fcberwachung erlaubt ist, wie lange die Daten gespeichert werden d\u00fcrfen, wie du eine \u00dcberwachungskamera kennzeichnen musst & vieles mehr.","og_url":"https:\/\/www.herold.at\/blog\/videoueberwachung-ueberwachungskamera\/","og_site_name":"Herold Blog","article_publisher":"https:\/\/www.facebook.com\/derherold","article_author":"#","article_published_time":"2020-01-13T05:03:54+00:00","article_modified_time":"2023-01-16T09:44:53+00:00","og_image":[{"width":830,"height":553,"url":"https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2019\/10\/Ueberwachungskamera.jpg","type":"image\/jpeg"}],"author":"Dominik Knapp","twitter_misc":{"Verfasst von":"Dominik Knapp","Gesch\u00e4tzte Lesezeit":"10 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.herold.at\/blog\/videoueberwachung-ueberwachungskamera\/","url":"https:\/\/www.herold.at\/blog\/videoueberwachung-ueberwachungskamera\/","name":"Video\u00fcberwachung | Rechtliche und technische Infos - HEROLD","isPartOf":{"@id":"https:\/\/www.herold.at\/blog\/#website"},"datePublished":"2020-01-13T05:03:54+00:00","dateModified":"2023-01-16T09:44:53+00:00","author":{"@id":"https:\/\/www.herold.at\/blog\/#\/schema\/person\/76f600ea6ba66f9ce2c49741903c213d"},"description":"Erfahre, wo Video\u00fcberwachung erlaubt ist, wie lange die Daten gespeichert werden d\u00fcrfen, wie du eine \u00dcberwachungskamera kennzeichnen musst & vieles mehr.","breadcrumb":{"@id":"https:\/\/www.herold.at\/blog\/videoueberwachung-ueberwachungskamera\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.herold.at\/blog\/videoueberwachung-ueberwachungskamera\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.herold.at\/blog\/videoueberwachung-ueberwachungskamera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.herold.at\/blog\/"},{"@type":"ListItem","position":2,"name":"Video\u00fcberwachung \u00d6sterreich: Die besten Systeme f\u00fcr Haus &#038; Wohnung"}]},{"@type":"WebSite","@id":"https:\/\/www.herold.at\/blog\/#website","url":"https:\/\/www.herold.at\/blog\/","name":"Herold Blog","description":"Ratgeber &amp; Blog von herold.at","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.herold.at\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de-DE"},{"@type":"Person","@id":"https:\/\/www.herold.at\/blog\/#\/schema\/person\/76f600ea6ba66f9ce2c49741903c213d","name":"Dominik Knapp","description":"SEO Text Guru Dominik Knapp ist SEO-Experte und Content Creator mit einem Faible f\u00fcr Sport, Star Wars und den Eurovision Song Contest. Er besch\u00e4ftigt sich seit 2013 mit Suchmaschinenoptimierung, Google Rankings und internen Verlinkungen. Zuvor war er mehrere Jahre als Sportjournalist t\u00e4tig.","sameAs":["http:\/\/www.herold.at","#","https:\/\/twitter.com\/#"],"url":"https:\/\/www.herold.at\/blog\/author\/dominik-knapp\/"}]}},"fimg_url":"https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2019\/10\/Ueberwachungskamera-560x360.jpg","_links":{"self":[{"href":"https:\/\/www.herold.at\/blog\/wp-json\/wp\/v2\/posts\/180917"}],"collection":[{"href":"https:\/\/www.herold.at\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.herold.at\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.herold.at\/blog\/wp-json\/wp\/v2\/users\/57"}],"replies":[{"embeddable":true,"href":"https:\/\/www.herold.at\/blog\/wp-json\/wp\/v2\/comments?post=180917"}],"version-history":[{"count":24,"href":"https:\/\/www.herold.at\/blog\/wp-json\/wp\/v2\/posts\/180917\/revisions"}],"predecessor-version":[{"id":255252,"href":"https:\/\/www.herold.at\/blog\/wp-json\/wp\/v2\/posts\/180917\/revisions\/255252"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.herold.at\/blog\/wp-json\/wp\/v2\/media\/182162"}],"wp:attachment":[{"href":"https:\/\/www.herold.at\/blog\/wp-json\/wp\/v2\/media?parent=180917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.herold.at\/blog\/wp-json\/wp\/v2\/categories?post=180917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.herold.at\/blog\/wp-json\/wp\/v2\/tags?post=180917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}