{"id":205857,"date":"2020-06-03T07:00:00","date_gmt":"2020-06-03T05:00:00","guid":{"rendered":"https:\/\/www.herold.at\/blog\/?p=205857"},"modified":"2025-05-28T09:25:39","modified_gmt":"2025-05-28T07:25:39","slug":"hypospadie-spezialisten-oesterreich","status":"publish","type":"post","link":"https:\/\/www.herold.at\/blog\/hypospadie-spezialisten-oesterreich\/","title":{"rendered":"Hypospadie: Wann muss man operieren?"},"content":{"rendered":"<figure id=\"attachment_210769\" aria-describedby=\"caption-attachment-210769\" style=\"width: 830px\" class=\"wp-caption alignnone\"><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-210769 size-full\" src=\"https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2019\/04\/Hypospadie-Adobe-Stock-c-SciePro.jpg\" alt=\"Eine grafische Darstellung des Verlauf der Harnr\u00f6hre.\" width=\"830\" height=\"410\" srcset=\"https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2019\/04\/Hypospadie-Adobe-Stock-c-SciePro.jpg 830w, https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2019\/04\/Hypospadie-Adobe-Stock-c-SciePro-300x148.jpg 300w, https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2019\/04\/Hypospadie-Adobe-Stock-c-SciePro-768x379.jpg 768w\" sizes=\"(max-width: 830px) 100vw, 830px\" \/><figcaption id=\"caption-attachment-210769\" class=\"wp-caption-text\">Wir verraten, welche M\u00f6glichkeiten zur Behandlung es bei Hypospadie gibt. Foto: Adobe Stock, (c) SciePro<\/figcaption><\/figure>\n<p>Unter Hypospadie versteht man eine <strong>angeborene Entwicklungsst\u00f6rung<\/strong>, bei der Jungen mit einer verk\u00fcrzten Harnr\u00f6hre auf die Welt kommen.\u00a0Diese h\u00e4ufige Fehlbildung kann unliebsame Folgen haben und\u00a0wird chirurgisch behandelt. Wie l\u00e4uft eine <strong>Hypospadie OP<\/strong> ab und welcher Arzt f\u00fchrt sie durch? Bei uns findest du alle wichtigen Informationen!<\/p>\n\n<h2><strong>Hypospadie \u2013 Was ist das?<\/strong><\/h2>\n<p>Bei der Hypospadie handelt es sich um eine <strong>angeborene\u00a0Fehlentwicklung<\/strong> der Harnr\u00f6hre, die dazu f\u00fchrt, dass das Organ <strong>k\u00fcrzer als normal<\/strong> angelegt ist. Die\u00a0\u00d6ffnung der Harnr\u00f6hre befindet sich deshalb nicht\u00a0an ihrer vorgesehenen Position.<\/p>\n<p>Anstelle der Spitze der Eichel m\u00fcndet die Harnr\u00f6hre je nach Schweregrad an der <strong>Unterseite des Penis<\/strong> oder im Bereich des Hodensacks bzw. Dammes. Bei <strong>M\u00e4dchen mit Hypospadie<\/strong> befindet sich die Harnr\u00f6hren\u00f6ffnung in der Scheidenwand.<\/p>\n<h3>Was bedeutet Hypospadie?<\/h3>\n<p>Der Begriff Hypospadie setzt sich aus den griechischen W\u00f6rtern <em>hypo\u00a0<\/em>(zu wenig) und <em>spadon<\/em> (Rinne, Spalte) zusammen, bezeichnet w\u00f6rtlich also die verk\u00fcrzte Harnr\u00f6hre dieser angeborenen St\u00f6rung.<\/p>\n<div class=\"content-box-yellow\"><strong>\u00dcbrigens:<\/strong>\u00a0Es gibt auch ein Gegenst\u00fcck zur Hypospadie: die Epispadie (<em>epi\u00a0<\/em>= dar\u00fcber). Bei dieser deutlich selteneren\u00a0St\u00f6rung liegt die erweiterte \u00d6ffnung der Harnr\u00f6hre an der Oberseite des Penis.<\/div>\n<h3><strong>Wie oft kommt Hypospadie vor?<\/strong><\/h3>\n<p>Hypospadie tritt nur selten bei M\u00e4dchen\u00a0auf und betrifft <strong>haupts\u00e4chlich Jungen<\/strong>.\u00a0Bei ihnen liegt die Chance, mit Hypospadie auf die Welt zu kommen, bei <strong>ca. 1 zu 200<\/strong>. Damit ist diese Entwicklungsst\u00f6rung die <strong>h\u00e4ufigste Fehlbildung<\/strong> der Harn- und Geschlechtsorgane bei m\u00e4nnlichen Neugeborenen.<\/p>\n<h3><strong>Wie entsteht Hypospadie?<\/strong><\/h3>\n<p>Eine Hypospadie ist die Folge einer Entwicklungshemmung in der 9. bis 13. Schwangerschaftswoche. Warum diese eintritt, ist bislang nicht genau bekannt. Wir wissen allerdings, dass sie <strong>famili\u00e4r geh\u00e4uft<\/strong>\u00a0auftritt. Neben erblichen Faktoren d\u00fcrften auch <strong>hormonelle Einfl\u00fcsse<\/strong> eine Rolle spielen, wie etwa ein Defekt der Bindungsstellen f\u00fcr m\u00e4nnliche Hormone. Auch die\u00a0<strong>Einnahme von Progesteron<\/strong> (Gelbk\u00f6rperhormon) w\u00e4hrend der Schwangerschaft scheint das Risiko f\u00fcr die Entwicklung zu erh\u00f6hen.<\/p>\n<p>Abgesehen davon leiden Beobachtungen zufolge <strong>untergewichtig geborene<\/strong> Babys \u00fcberdurchschnittlich h\u00e4ufig an einer Hypospadie. Auch Umweltfaktoren, wie die Einwirkung bestimmter <strong>Schadstoffe<\/strong> (z. B. Dioxin, Pestizide), werden als m\u00f6gliche Ausl\u00f6ser diskutiert.<\/p>\n<h3><strong>Wie zeigt sich Hypospadie?<\/strong><\/h3>\n<p>Bei Hypospadie ist die Harnr\u00f6hre verk\u00fcrzt und endet deshalb nicht an der Spitze des Penis, sondern darunter. Je nachdem, in welchem Bereich sich ihre \u00d6ffnung befindet, unterteilt die Medizin diese Entwicklungsst\u00f6rung in\u00a0drei Kategorien.<\/p>\n<ul>\n<li><strong>vordere Hypospadie<\/strong> (Grad I): Die Harnr\u00f6hre m\u00fcndet an der Unterseite der Eichel.<\/li>\n<li><strong>mittlere Hypospadie<\/strong> (Grad II): Die Harnr\u00f6hren\u00f6ffnung sitzt an der Mitte des Penisschaftes.<\/li>\n<li><strong>hintere Hypospadie<\/strong> (Grad III): Die Harnr\u00f6hre endet am Hodensack oder Damm.<\/li>\n<\/ul>\n<p>Unter diesen Formen tritt die\u00a0vordere Hypospadie <strong>am h\u00e4ufigsten<\/strong>\u00a0auf. In diesem Fall liegt meistens auch eine <strong>Spaltung der Vorhaut<\/strong> vor. Dann umh\u00fcllt die Vorhaut nicht die gesamte Eichel, sondern ist an der Penisunterseite gespalten und liegt kapuzenf\u00f6rmig \u00fcber der Spitze des Penis. Der untere Teil der Vorhaut fehlt also, w\u00e4hrend der obere Teil sehr gro\u00df ist. Somit bildet sich eine Art Vorhautsch\u00fcrze.<\/p>\n<figure id=\"attachment_210766\" aria-describedby=\"caption-attachment-210766\" style=\"width: 830px\" class=\"wp-caption alignnone\"><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-210766 size-full\" src=\"https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2019\/04\/Hypospadie-Adobe-Stock-c-Oleksandr.jpg\" alt=\"Ein Mann bei einem Arzt f\u00fcr Urologie und Chirurgie.\" width=\"830\" height=\"410\" srcset=\"https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2019\/04\/Hypospadie-Adobe-Stock-c-Oleksandr.jpg 830w, https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2019\/04\/Hypospadie-Adobe-Stock-c-Oleksandr-300x148.jpg 300w, https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2019\/04\/Hypospadie-Adobe-Stock-c-Oleksandr-768x379.jpg 768w\" sizes=\"(max-width: 830px) 100vw, 830px\" \/><figcaption id=\"caption-attachment-210766\" class=\"wp-caption-text\">Der Verlauf der Harnr\u00f6hre kann auch bei Erwachsenen korrigiert werden. Foto: Adobe Stock, (c) Oleksandr<\/figcaption><\/figure>\n<p>Bei <strong>ausgepr\u00e4gter Hypospadie<\/strong> ist der Penis durch die verk\u00fcrzte Harnr\u00f6hre bzw. Mitbeteiligung des Harnr\u00f6hrenschwellk\u00f6rpers oft <strong>nach unten gekr\u00fcmmt<\/strong>. In manchen F\u00e4llen verst\u00e4rkt ein derber, bindegewebiger Strang (die sogenannte <strong>Chorda<\/strong>) diesen Effekt zus\u00e4tzlich. Diese Kr\u00fcmmung kann schmerzhaft sein und zu einem <strong>nach unten abgelenkten Harnstrahl<\/strong> f\u00fchren. Das kann kann es unm\u00f6glich machen im Stehen zu urinieren.\u00a0Ohne Therapie k\u00f6nnen bei Patienten sp\u00e4ter auch Schwierigkeiten beim Geschlechtsverkehr auftreten.<\/p>\n<p>Abgesehen davon kann zus\u00e4tzlich ein <strong>Leistenbruch<\/strong> vorhanden sein und der Hodensack zu weit oben liegen oder zweigeteilt sein.\u00a0Zudem stellt das ver\u00e4nderte Erscheinungsbild des\u00a0Genitals oft eine <strong>psychische Belastung<\/strong> dar.<\/p>\n<h3><strong>Wie erkennt der Arzt eine Hypospadie? <\/strong><\/h3>\n<p>Eine Hypospadie l\u00e4sst sich in der Regel\u00a0durch die\u00a0<strong>Begutachtung des Intimbereichs<\/strong> feststellen (Blickdiagnose). Da die Entwicklungsst\u00f6rung recht h\u00e4ufig mit anderen Fehlbildungen der Harn- und Geschlechtsorgane gemeinsam auftritt,\u00a0sucht der Arzt aber\u00a0mittels Tastuntersuchung und Ultraschall immer auch nach <strong>weiteren St\u00f6rungen<\/strong>, wie etwa:<\/p>\n<ul>\n<li>nicht im Hodensack gelegenen Hoden<\/li>\n<li>einem zu weit oben liegenden oder zweigeteilten Hodensack<\/li>\n<li>einem Leistenbruch<\/li>\n<li>Fehlbildungen im oberen Harntrakt wie z. B. Ureterabgangsstenosen, einem <a href=\"https:\/\/www.herold.at\/blog\/harnreflux\/\" target=\"_blank\" rel=\"noopener noreferrer\">Harnreflux<\/a> oder Nierenagenesie (Fehlen einer Niere).<\/li>\n<\/ul>\n<p>Findet er Hinweise auf eine <strong>Intersexualit\u00e4t<\/strong> (Vorkommen von m\u00e4nnlichen und weiblichen Geschlechtsmerkmalen, keine eindeutige Geschlechtszugeh\u00f6rigkeit), k\u00f6nnen weitere diagnostische Schritte wie etwa Hormonbestimmungen oder Untersuchungen des Erbguts folgen.<\/p>\n<div class=\"content-box-yellow\">Intersexualit\u00e4t ist <strong>keine Krankheit<\/strong> und nicht jede k\u00f6rperliche Abweichung muss auf medizinischem Weg &#8220;korrigiert&#8221; werden. Im Gegenteil: Experten raten dazu, auf nicht notwendige Eingriffe zu verzichten, da diese h\u00e4ufig als traumatisch erlebt werden. Auf der Website des <a href=\"https:\/\/vimoe.at\/\" target=\"_blank\" rel=\"noopener noreferrer\">Verein Intergeschlechtlicher Menschen \u00d6sterreich<\/a> findest du Beratungsangebote und weitere Informationen.<\/div>\n<h2><strong>Wie behandelt man Hypospadie?<\/strong><\/h2>\n<p>Die Therapie\u00a0der St\u00f6rung besteht in einer <strong>chirurgischen Berichtigung<\/strong>. Im Idealfall\u00a0wird diese in einer einzigen Operation durchgef\u00fchrt. Bei einem stark ausgepr\u00e4gten Erscheinungsbild k\u00f6nnen jedoch mehrere Eingriffe notwendig sein.<\/p>\n<p>Der Kinderchirurgie bzw.\u00a0-urologie stehen f\u00fcr die\u00a0Therapie\u00a0<strong>zahlreiche Operationstechniken<\/strong> zur Verf\u00fcgung. Sie unterscheiden sich hinsichtlich\u00a0des Risikos f\u00fcr Komplikationen sowie der kosmetischen und funktionalen Ergebnisse. Welche Technik zum Einsatz kommt, h\u00e4ngt unter anderem von der <strong>Lage der Harnr\u00f6hrenm\u00fcndung<\/strong> und dem <strong>Ausma\u00df der Verkr\u00fcmmung<\/strong> des Penisschaftes ab.<\/p>\n<h3><strong>Hypospadie: Warum operieren?<\/strong><\/h3>\n<p>Eine Hypospadie OP gew\u00e4hrleistet f\u00fcr betroffene Kinder <strong>Schmerzfreiheit<\/strong> und eine sp\u00e4tere <strong>optimale Entwicklung<\/strong>.\u00a0Die operative Korrektur hat zum Ziel:<\/p>\n<ul>\n<li>ein ungehindertes und schmerzfreies Wasserlassen zu erreichen.<\/li>\n<li>die Weiterleitung\u00a0von Sperma durch die Harnr\u00f6hre zu erm\u00f6glichen.<\/li>\n<li>durch die Aufrichtung der Penisverkr\u00fcmmung\u00a0Erektionen in gerader Position und ein normales Sexualleben m\u00f6glich zu machen.<\/li>\n<li>psychische Belastungen wie z. B. Angst vor \u00f6ffentlichen Einrichtungen, Schwimmb\u00e4dern, Gemeinschaftstoiletten etc. oder Einschr\u00e4nkungen im m\u00e4nnlichen Selbstwertgef\u00fchl zu verhindern.<\/li>\n<\/ul>\n<h3>Hypospadie Spezialisten \u00d6sterreich &#8211; Kontakt<\/h3>\n<p>Die\u00a0operative Korrektur der Hypospadie\u00a0f\u00e4llt in das Fachgebiet der <strong>Kinderurologie bzw. Kinderchirurgie<\/strong>. Entsprechende Abteilungen findest du in vielen Krankenh\u00e4usern in \u00d6sterreich. F\u00fcr die Voruntersuchung und eine Einsch\u00e4tzung \u00fcber die chirurgischen M\u00f6glichkeiten wendest du dich am besten an einen <a href=\"https:\/\/www.herold.at\/blog\/kinderurologie-schwerpunkte\/\" target=\"_blank\" rel=\"noopener noreferrer\">Kinderurologen<\/a>. Wir haben einige Spezialisten f\u00fcr dich recherchiert, die bestens mit dem Thema Hypospadie vertraut sind.<\/p>\n<h4>Dr. Franklin K\u00fchhas \u2013 Wien 1080<\/h4>\n<p><a href=\"https:\/\/www.herold.at\/gelbe-seiten\/wien\/19PDc\/k%C3%BChhas-franklin-dr\/\" target=\"_blank\" rel=\"noopener noreferrer\">Dr. Franklin K\u00fchhas<\/a> ist Facharzt f\u00fcr Urologie und Spezialist auf dem Gebiet der Genitalchirurgie und rekonstruktiven Andrologie. In seiner Praxis in Wien bietet er Patienten kosmetische Eingriffe wie Penisvergr\u00f6\u00dferungen oder die Korrektur einer Peniskr\u00fcmmung. Auch die <strong>Hypospadie OP bei Erwachsenen<\/strong> geh\u00f6rt zu seinem Angebot.<\/p>\n<p><strong>Kontakt:\u00a0<\/strong><a href=\"https:\/\/www.herold.at\/gelbe-seiten\/wien\/19PDc\/k%C3%BChhas-franklin-dr\/\" target=\"_blank\" rel=\"noopener noreferrer\">Dr. Franklin K\u00fchhas, 1080 Wien<\/a><\/p>\n<h4>Dr. Romana Altenhuber\u00a0\u2013 Wien 1180<\/h4>\n<p>Die Fach\u00e4rztin f\u00fcr Urologie <a href=\"https:\/\/www.herold.at\/gelbe-seiten\/wien\/dPx6w\/altenhuber-romana-dr-urologische-ordination-f%C3%BCr-kinder-und-frauen\/\" target=\"_blank\" rel=\"noopener noreferrer\">Dr. Romana Altenhuber<\/a> hat sich auf die Behandlung von Frauen und Kindern spezialisiert. Als Expertin im Bereich der Kinderurologie ber\u00e4t sie Eltern bei Problemen wie Hypospadie, einem Hodenhochstand oder der <a href=\"https:\/\/www.herold.at\/blog\/phimose-vorhautverengung-operation\/\" target=\"_blank\" rel=\"noopener noreferrer\">Phimose<\/a>.<\/p>\n<p><strong>Kontakt:\u00a0<\/strong><a href=\"https:\/\/www.herold.at\/gelbe-seiten\/wien\/dPx6w\/altenhuber-romana-dr-urologische-ordination-f%C3%BCr-kinder-und-frauen\/\" target=\"_blank\" rel=\"noopener noreferrer\">Dr. Romana Altenhuber, 1180 Wien<\/a><\/p>\n<h4>Dr. Josef Oswald\u00a0\u2013 Linz 4020<\/h4>\n<p><a href=\"https:\/\/www.herold.at\/gelbe-seiten\/linz\/2cHL7\/oswald-josef-univ-doz-prim-dr\/\" target=\"_blank\" rel=\"noopener noreferrer\">Dr. Josef Oswald<\/a> ist Primar der Kinderurologischen Abteilung der Ordensklinik in Linz. Mit \u00fcber 20 Jahren Erfahrung in Bereich der Kinderurologie kennt er alle Behandlungsm\u00f6glichkeiten bei angeborenen St\u00f6rungen. Seinen Wissensschatz teilt er mit Patienten auch in seiner privaten Ordination.<\/p>\n<p><strong>Kontakt:\u00a0<\/strong><a href=\"https:\/\/www.herold.at\/gelbe-seiten\/linz\/2cHL7\/oswald-josef-univ-doz-prim-dr\/\" target=\"_blank\" rel=\"noopener noreferrer\">Dr. Josef Oswald, 4020 Linz<\/a><\/p>\n<h4>Dr. Bernhard Herrnegger\u00a0\u2013 Innsbruck 6020<\/h4>\n<p>Der Urologe <a href=\"https:\/\/www.herold.at\/gelbe-seiten\/innsbruck\/s39dn\/herrnegger-bernhard-dr\/\" target=\"_blank\" rel=\"noopener noreferrer\">Dr. Bernhard Herrnegger<\/a> behandelt sowohl erwachsene Patienten als auch Kinder. In seiner Praxis f\u00fchrt alle n\u00f6tigen Untersuchungen durch, um den Schweregrad einer Hypospadie zu beurteilen und die n\u00e4chsten Schritte in die Wege zu leiten.<\/p>\n<p><strong>Kontakt:\u00a0<\/strong><a href=\"https:\/\/www.herold.at\/gelbe-seiten\/innsbruck\/s39dn\/herrnegger-bernhard-dr\/\" target=\"_blank\" rel=\"noopener noreferrer\">Dr. Bernhard Herrnegger, 6020 Innsbruck<\/a><\/p>\n<h4>Dr. Dagmar Strohmeyer\u00a0\u2013 6271 Uderns<\/h4>\n<p><a href=\"https:\/\/www.herold.at\/gelbe-seiten\/uderns\/Hdqb5\/priv-doz-dr-med-dagmar-strohmeyer\/\" target=\"_blank\" rel=\"noopener noreferrer\">Dr. Dagmar Strohmeyer<\/a>\u00a0bietet Patienten eine umfassende urologische Betreuung. Auch die Korrektur angeborener St\u00f6rungen\u00a0geh\u00f6rt zu ihrem Leistungsspektrum. Station\u00e4re Operationen f\u00fchrt sie in der Klinik Sanatorium Kettenbr\u00fccke in Innsbruck durch.<\/p>\n<p><strong>Kontakt:\u00a0<\/strong><a href=\"https:\/\/www.herold.at\/gelbe-seiten\/uderns\/Hdqb5\/priv-doz-dr-med-dagmar-strohmeyer\/\" target=\"_blank\" rel=\"noopener noreferrer\">Dr. Dagmar Strohmeyer, 6271 Uderns<\/a><\/p>\n<h2><strong>Wie l\u00e4uft eine Hypospadie OP ab? <\/strong><\/h2>\n<p>Das Ziel einer Hypospadie OP ist ein\u00a0aufrechter Penis mit einer Harnr\u00f6hren\u00f6ffnung in regul\u00e4rer Position, also an der Spitze der Eichel. Soweit die Voraussetzungen es zulassen, wird ein m\u00f6glichst \u201cnormales\u201c Aussehen angestrebt. Das hei\u00dft, die Operation beinhaltet die <strong>Verlagerung der Harnr\u00f6hren\u00f6ffnung<\/strong>\u00a0an die Spitze der Eichel,\u00a0wozu auch eine\u00a0<strong>Verl\u00e4ngerung der verk\u00fcrzten Harnr\u00f6hre<\/strong>,\u00a0die <strong>Neubildung oder Beschneidung der Vorhaut<\/strong>\u00a0sowie die\u00a0<strong>Beseitigung der Penisverkr\u00fcmmung<\/strong>\u00a0notwendig sein kann.<\/p>\n<p>Hierzu gibt es <strong>verschiedene Operationstechniken<\/strong>, deren Anwendung sich nach den jeweiligen Gegebenheiten richtet. Am einfachsten zu korrigieren sind Hypospadien, bei denen die Harnr\u00f6hre an der Eichel oder am Eichelrand endet und keine Penisverkr\u00fcmmung vorliegt. Die Technik, die in diesem Fall zum Einsatz kommt, tr\u00e4gt den Namen\u00a0<strong>MAGPI<\/strong>:\u00a0meatal advancement and glanuloplasty. Dabei handelt es sich um die\u00a0<strong>Vorverlagerung der Harnr\u00f6hrenm\u00fcndung<\/strong>\u00a0und kosmetische Anpassung der Eichel durch\u00a0eine besondere Schnittf\u00fchrung.<\/p>\n<figure id=\"attachment_210775\" aria-describedby=\"caption-attachment-210775\" style=\"width: 830px\" class=\"wp-caption alignnone\"><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-210775 size-full\" src=\"https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2019\/04\/Hypospadie-Adobe-Stock-c-Kadmy.jpg\" alt=\"Ein Team an \u00c4rzten f\u00fcr Chirurgie und Kinderurologie im Operationssaal einer Klinik.\" width=\"830\" height=\"410\" srcset=\"https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2019\/04\/Hypospadie-Adobe-Stock-c-Kadmy.jpg 830w, https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2019\/04\/Hypospadie-Adobe-Stock-c-Kadmy-300x148.jpg 300w, https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2019\/04\/Hypospadie-Adobe-Stock-c-Kadmy-768x379.jpg 768w\" sizes=\"(max-width: 830px) 100vw, 830px\" \/><figcaption id=\"caption-attachment-210775\" class=\"wp-caption-text\">Durch die Operation der Hypospadie kann die normale Funktion des Penis gew\u00e4hrleistet werden. Foto: Adobe Stock, (c) Kadmy<\/figcaption><\/figure>\n<p><strong>Je<\/strong><strong>\u00a0weiter unten <\/strong>die Harnr\u00f6hrenm\u00fcndung liegt,\u00a0<strong>umso komplizierter<\/strong> gestaltet sich der Eingriff. Denn dann kann es notwendig sein, die Harnr\u00f6hre von den Schwellk\u00f6rpern zu l\u00f6sen und in gedehntem Zustand bis an die Eichelspitze vorzuziehen. In einigen F\u00e4llen kommt eine <strong>Harnr\u00f6hrenplastik<\/strong> zum Einsatz,\u00a0bei der die verk\u00fcrzte Harnr\u00f6hre verl\u00e4ngert wird indem man den fehlenden Teil aus anderem Gewebe formt. Daher sollten\u00a0Kinder vor dem Operationstermin <strong>nicht beschnitten<\/strong> werden, weil die Vorhautsch\u00fcrze unter Umst\u00e4nden noch zur Neubildung der Harnr\u00f6hre dient.<\/p>\n<p>Bei hochgradiger Hypospadie k\u00f6nnen auch <strong>mehrere Operationen<\/strong> erforderlich sein. Zudem kann dem Eingriff eine <strong>mehrw\u00f6chige Salbenbehandlung<\/strong> mit einem lokal wirksamen <strong>Testosteronpr\u00e4parat <\/strong>vorausgehen. Sie dient zur Verbesserung der Durchblutung und Verfestigung der Penishaut, sowie zur vor\u00fcbergehenden Vergr\u00f6\u00dferung des Penis. Auf diesem Weg wird das Risiko f\u00fcr Komplikationen gesenkt.<\/p>\n<h3><strong>Wann sollte\u00a0eine Hypospadie OP\u00a0stattfinden?<\/strong><\/h3>\n<p>Grunds\u00e4tzlich ist eine Operation nicht nur bei Kindern, sondern auch bei Erwachsenen m\u00f6glich.\u00a0Allerdings liegt der ideale Zeitpunkt\u00a0f\u00fcr den Eingriff\u00a0im Alter zwischen <strong>12 und 18 Monaten<\/strong>, also noch w\u00e4hrend die betroffenen Kinder Windeln tragen. In diesem Alter ist der Penis noch nicht als Teil des eigenen K\u00f6rperbildes in die Wahrnehmung ger\u00fcckt.\u00a0Falls eine Verengung der Harnr\u00f6hre den\u00a0<strong>Harnfluss behindert<\/strong>,\u00a0muss unter Umst\u00e4nden aber auch schon\u00a0<strong>fr\u00fcher operiert werden<\/strong>.<\/p>\n<p>Je l\u00e4nger Eltern mit der Operation warten, desto eher nehmen betroffene Kinder ihren K\u00f6rper als &#8220;anders&#8221; war. Neben der kosmetischen Abweichung r\u00fccken auch <strong>funktionale Unterschiede<\/strong> in ihre Aufmerksamkeit. Etwa, dass ihr Harnstrahl nicht nach vorne, sondern nach unten gerichtet ist. Oder\u00a0sp\u00e4ter, dass wegen der Kr\u00fcmmung des\u00a0Schaftes keine gerade Erektion m\u00f6glich ist.<\/p>\n<p>Zudem zeigt die chirurgische Korrektur in den ersten beiden Lebensjahren\u00a0<strong>bessere Ergebnisse<\/strong> als etwa im Jugend- oder Erwachsenenalter. Sie hat auch den Vorteil, dass die Buben bei Eintritt in den Kindergarten bereits einen normal ausgebildeten Penis aufweisen.<\/p>\n<h3><strong>Wie\u00a0lange muss man bei einer Hypospadie OP im Krankenhaus bleiben?<\/strong><\/h3>\n<p>Wie viel Zeit die Operation und Genesung in Anspruch nehmen, h\u00e4ngt von ihrer Auspr\u00e4gung und\u00a0den individuellen anatomischen Gegebenheiten ab. In der Regel dauert die Operation <strong>1 bis 4 Stunden<\/strong>. Bei sehr geringen Auspr\u00e4gungen kann die Korrektur in einigen F\u00e4llen auch ambulant erfolgen.<\/p>\n<p>Bei einem station\u00e4ren Aufenthalt richtet sich die Entlassung aus dem Krankenhaus nach der <strong>Schwere des Eingriffs<\/strong>, etwaigen <strong>Komplikationen<\/strong> und danach, wann bei Patienten das Wasserlassen wieder gut funktioniert. Die Entlassung erfolgt \u00fcblicherweise nach <strong>vier bis f\u00fcnf Tagen<\/strong>.<\/p>\n<h3><strong>Was passiert nach einer Hypospadie OP?<\/strong><\/h3>\n<p>Nach der Operation ist eine <strong>Ruhigstellung des Penis<\/strong> per straffem Verband und oft auch eine vor\u00fcbergehende Ableitung des Urins \u00fcber einen <strong>Blasenkatheter<\/strong> erforderlich, um den Behandlungserfolg zu sichern. Meist wird dieser Kunststoffschlauch in die Harnr\u00f6hre eingelegt. Manchmal ist es aber notwendig, \u00fcber einen kleinen Hautschnitt oberhalb des Schambeins einen Blasenkatheter zu setzen, der den Harn direkt aus der Blase leitet. Der Katheter verbleibt \u00fcblicherweise f\u00fcr <strong>zwei bis zw\u00f6lf Tage<\/strong> in seiner Position.<\/p>\n<p>Bis zur Entfernung des Katheters sollte das Kind <strong>haupts\u00e4chlich liegen<\/strong>, um das\u00a0Ergebnis der Operation und die Wundheilung nicht zu gef\u00e4hrden. Nach dem Ziehen des Katheters kann es dann allm\u00e4hlich vorsichtig aufstehen und herumlaufen.<\/p>\n<figure id=\"attachment_210778\" aria-describedby=\"caption-attachment-210778\" style=\"width: 830px\" class=\"wp-caption alignnone\"><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-210778 size-full\" src=\"https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2019\/04\/Hypospadie-Adobe-Stock-c-Mladen.jpg\" alt=\"Ein Baby in R\u00fcckenlage dessen Windel gewechselt wird.\" width=\"830\" height=\"410\" srcset=\"https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2019\/04\/Hypospadie-Adobe-Stock-c-Mladen.jpg 830w, https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2019\/04\/Hypospadie-Adobe-Stock-c-Mladen-300x148.jpg 300w, https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2019\/04\/Hypospadie-Adobe-Stock-c-Mladen-768x379.jpg 768w\" sizes=\"(max-width: 830px) 100vw, 830px\" \/><figcaption id=\"caption-attachment-210778\" class=\"wp-caption-text\">Die\u00a0Therapie in jungen Jahren erlaubt eine normale Entwicklung f\u00fcr betroffene Kinder. Foto: Adobe Stock, (c) Mladen<\/figcaption><\/figure>\n<p>Um postoperative Schmerzen zu minimieren gilt es in der ersten Zeit nach dem Eingriff eine <strong>Bauchlage zu vermeiden<\/strong> sowie m\u00f6glichst <strong>weite Hosen und Windeln<\/strong> zu tragen. Au\u00dferdem darf das operierte Kind nicht am Schritt hochgehoben werden. Das Fahren mit\u00a0dem Bobby-Car, Dreirad oder Fahrrad und\u00a0Spielzeuge wie\u00a0ein Schaukelpferd sind tabu. Auch sollte das Kind <strong>reichlich trinken<\/strong>, um eventuell in die Blase geratene Keime auszusp\u00fclen.<\/p>\n<p>Falls eines der folgenden Symptome auftritt, sollten Eltern den Arzt aufsuchen:<\/p>\n<ul>\n<li>Fieber<\/li>\n<li>starke Schmerzen<\/li>\n<li>eine starken R\u00f6tung des Wundbereichs<\/li>\n<li>ein Harnverhalt<\/li>\n<\/ul>\n<h3><strong>Welche Komplikationen kann es bei einer Hypospadie OP geben? <\/strong><\/h3>\n<p>Auch wenn die meisten Korrekturen einer Hypospadie erfolgreich verlaufen, kommt es vor allem bei hochgradiger Formen\u00a0doch vor, dass sich die Fehlbildung <strong>nicht vollst\u00e4ndig<\/strong> oder nicht auf Anhieb operativ korrigieren l\u00e4sst. Ansonsten bergen solche Operationen \u2013 ebenso wie andere chirurgische Eingriffe \u2013 <strong>Risiken<\/strong> wie Schwellungen, Nachblutungen, Wundinfektionen, \u00fcberschie\u00dfende Narbenbildung und Funktions- oder Wundheilungsst\u00f6rungen.<\/p>\n<p>Recht h\u00e4ufig kommt es nach der Operation zur Bildung einer <a href=\"https:\/\/www.herold.at\/blog\/fistel\/\" target=\"_blank\" rel=\"noopener noreferrer\">Fistel<\/a>, erkennbar durch einen zweiten Harnstrahl oder ein Harntr\u00e4ufeln. Oder zu einer <strong>Harnr\u00f6hrenstriktur<\/strong> (Verengung der Harnr\u00f6hre) durch Narben.\u00a0Ebenso m\u00f6glich ist die Entwicklung einer\u00a0<strong>Meatusstenose<\/strong> (Enge der neu gebildeten Harnr\u00f6hren\u00f6ffnung), von narbigen Verziehungen der Harnr\u00f6hre oder\u00a0Talgansammlungen.<\/p>\n<p>Unter Umst\u00e4nden ist ein <strong>erneuter Eingriff<\/strong> notwendig, um diese Komplikationen zu beseitigen. Wie beispielsweise ein Erweiterungsschlitz bei Verengungen. Zudem kann es zu einer neuerlichen Fehllage der Harnr\u00f6hrenm\u00fcndung oder wiederkehrenden Harnwegsinfektionen kommen.<\/p>\n<h3>Die besten Urologen in deiner N\u00e4he:<\/h3>\n<div class=\"herold_bl\"><div class=\"herold_bl_col\"><div class=\"herold_bl_col_inner\"><div class=\"herold_bl_text\"><p>\u2192 <a href=\"https:\/\/www.herold.at\/gelbe-seiten\/wien\/urologe\/\" target=\"_blank\">Wien<\/a><\/p><\/div><div class=\"herold_bl_last\"><\/div><div class=\"tobelastincol\"><\/div><div class=\"herold_bl_text\"><p>\u2192 <a href=\"https:\/\/www.herold.at\/gelbe-seiten\/burgenland\/urologe\/\" target=\"_blank\">Burgenland<\/a><\/p><\/div><div class=\"herold_bl_last\"><\/div><div class=\"tobelastincol\"><\/div><div class=\"herold_bl_text\"><p>\u2192 <a href=\"https:\/\/www.herold.at\/gelbe-seiten\/salzburg\/urologe\/\" target=\"_blank\">Salzburg<\/a><\/p><\/div><div class=\"herold_bl_last\"><\/div><div class=\"tobelastincol\"><\/div><\/div><\/div><div class=\"herold_bl_col\"><div class=\"herold_bl_col_inner\"><div class=\"herold_bl_text\"><p>\u2192 <a href=\"https:\/\/www.herold.at\/gelbe-seiten\/nieder\u00f6sterreich\/urologe\/\" target=\"_blank\">Nieder\u00f6sterreich<\/a><\/p><\/div><div class=\"herold_bl_last\"><\/div><div class=\"tobelastincol\"><\/div><div class=\"herold_bl_text\"><p>\u2192 <a href=\"https:\/\/www.herold.at\/gelbe-seiten\/steiermark\/urologe\/\" target=\"_blank\">Steiermark<\/a><\/p><\/div><div class=\"herold_bl_last\"><\/div><div class=\"tobelastincol\"><\/div><div class=\"herold_bl_text\"><p>\u2192 <a href=\"https:\/\/www.herold.at\/gelbe-seiten\/tirol\/urologe\/\" target=\"_blank\">Tirol<\/a><\/p><\/div><div class=\"herold_bl_last\"><\/div><div class=\"tobelastincol\"><\/div><\/div><\/div><div class=\"herold_bl_col\"><div class=\"herold_bl_col_inner\"><div class=\"herold_bl_text\"><p>\u2192 <a href=\"https:\/\/www.herold.at\/gelbe-seiten\/ober\u00f6sterreich\/urologe\/\" target=\"_blank\">Ober\u00f6sterreich<\/a><\/p><\/div><div class=\"herold_bl_last\"><\/div><div class=\"tobelastincol\"><\/div><div class=\"herold_bl_text\"><p>\u2192 <a href=\"https:\/\/www.herold.at\/gelbe-seiten\/k\u00e4rnten\/urologe\/\" target=\"_blank\">K\u00e4rnten<\/a><\/p><\/div><div class=\"herold_bl_last\"><\/div><div class=\"tobelastincol\"><\/div><div class=\"herold_bl_text\"><p>\u2192 <a href=\"https:\/\/www.herold.at\/gelbe-seiten\/vorarlberg\/urologe\/\" target=\"_blank\">Vorarlberg<\/a><\/p><\/div><div class=\"herold_bl_last\"><\/div><div class=\"tobelastincol\"><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Unter Hypospadie versteht man eine angeborene Entwicklungsst\u00f6rung, bei der Jungen mit einer verk\u00fcrzten Harnr\u00f6hre auf die Welt kommen.\u00a0Diese h\u00e4ufige Fehlbildung kann unliebsame Folgen haben und\u00a0wird chirurgisch behandelt. Wie l\u00e4uft eine Hypospadie OP ab und welcher Arzt f\u00fchrt sie durch? Bei uns findest du alle wichtigen Informationen! Hypospadie \u2013 Was ist das? Bei der Hypospadie handelt es sich um eine angeborene\u00a0Fehlentwicklung der Harnr\u00f6hre, die dazu f\u00fchrt, dass das Organ k\u00fcrzer als normal angelegt ist. Die\u00a0\u00d6ffnung der Harnr\u00f6hre befindet sich deshalb nicht\u00a0an ihrer vorgesehenen Position. Anstelle der Spitze der Eichel m\u00fcndet die Harnr\u00f6hre je nach Schweregrad an der Unterseite des Penis oder im Bereich des Hodensacks bzw. Dammes. Bei M\u00e4dchen mit Hypospadie befindet sich die Harnr\u00f6hren\u00f6ffnung in der Scheidenwand. Was bedeutet Hypospadie? Der Begriff Hypospadie setzt sich aus den griechischen W\u00f6rtern hypo\u00a0(zu wenig) und spadon (Rinne, Spalte) zusammen, bezeichnet w\u00f6rtlich also die verk\u00fcrzte Harnr\u00f6hre dieser angeborenen St\u00f6rung. \u00dcbrigens:\u00a0Es gibt auch ein Gegenst\u00fcck zur Hypospadie: die Epispadie (epi\u00a0= dar\u00fcber). Bei dieser deutlich selteneren\u00a0St\u00f6rung liegt die erweiterte \u00d6ffnung der Harnr\u00f6hre an der Oberseite des Penis. Wie oft kommt Hypospadie vor? Hypospadie tritt nur selten bei M\u00e4dchen\u00a0auf und betrifft haupts\u00e4chlich Jungen.\u00a0Bei ihnen liegt die Chance, mit Hypospadie auf die Welt zu kommen, bei ca. 1 zu 200. Damit ist diese Entwicklungsst\u00f6rung die h\u00e4ufigste Fehlbildung der Harn- und Geschlechtsorgane bei m\u00e4nnlichen Neugeborenen. Wie entsteht Hypospadie? Eine Hypospadie ist die Folge einer Entwicklungshemmung in der 9. bis 13. Schwangerschaftswoche. Warum diese eintritt, ist bislang nicht genau bekannt. Wir wissen allerdings, dass sie famili\u00e4r geh\u00e4uft\u00a0auftritt. Neben erblichen Faktoren d\u00fcrften auch hormonelle Einfl\u00fcsse eine Rolle spielen, wie etwa ein Defekt der Bindungsstellen f\u00fcr m\u00e4nnliche Hormone. Auch die\u00a0Einnahme von Progesteron (Gelbk\u00f6rperhormon) w\u00e4hrend der Schwangerschaft scheint das Risiko f\u00fcr die Entwicklung zu erh\u00f6hen. Abgesehen davon leiden Beobachtungen zufolge untergewichtig geborene Babys \u00fcberdurchschnittlich h\u00e4ufig an einer Hypospadie. Auch Umweltfaktoren, wie die Einwirkung bestimmter Schadstoffe (z. B. Dioxin, Pestizide), werden als m\u00f6gliche Ausl\u00f6ser diskutiert. Wie zeigt sich Hypospadie? Bei Hypospadie ist die Harnr\u00f6hre verk\u00fcrzt und endet deshalb nicht an der Spitze des Penis, sondern darunter. Je nachdem, in welchem Bereich sich ihre \u00d6ffnung befindet, unterteilt die Medizin diese Entwicklungsst\u00f6rung in\u00a0drei Kategorien. vordere Hypospadie (Grad I): Die Harnr\u00f6hre m\u00fcndet an der Unterseite der Eichel. mittlere Hypospadie (Grad II): Die Harnr\u00f6hren\u00f6ffnung sitzt an der Mitte des Penisschaftes. hintere Hypospadie (Grad III): Die Harnr\u00f6hre endet am Hodensack oder Damm. Unter diesen Formen tritt die\u00a0vordere Hypospadie am h\u00e4ufigsten\u00a0auf. In diesem Fall liegt meistens auch eine Spaltung der Vorhaut vor. Dann umh\u00fcllt die Vorhaut nicht die gesamte Eichel, sondern ist an der Penisunterseite gespalten und liegt kapuzenf\u00f6rmig \u00fcber der Spitze des Penis. Der untere Teil der Vorhaut fehlt also, w\u00e4hrend der obere Teil sehr gro\u00df ist. Somit bildet sich eine Art Vorhautsch\u00fcrze. Bei ausgepr\u00e4gter Hypospadie ist der Penis durch die verk\u00fcrzte Harnr\u00f6hre bzw. Mitbeteiligung des Harnr\u00f6hrenschwellk\u00f6rpers oft nach unten gekr\u00fcmmt. In manchen F\u00e4llen verst\u00e4rkt ein derber, bindegewebiger Strang (die sogenannte Chorda) diesen Effekt zus\u00e4tzlich. Diese Kr\u00fcmmung kann schmerzhaft sein und zu einem nach unten abgelenkten Harnstrahl f\u00fchren. Das kann kann es unm\u00f6glich machen im Stehen zu urinieren.\u00a0Ohne Therapie [&hellip;]<\/p>\n","protected":false},"author":175,"featured_media":210772,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[247],"tags":[],"acf":[],"yoast_head":"\n<title>Hypospadie: Wenn die Harnr\u00f6hre operiert werden muss - HEROLD.at<\/title>\n<meta name=\"description\" content=\"Bei einer Hypospadie m\u00fcndet die Harnr\u00f6hre an der Unterseite des Penis. Diese angeborene Entwicklungsst\u00f6rung kann durch eine Operation korrigiert werden.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.herold.at\/blog\/hypospadie-spezialisten-oesterreich\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hypospadie: Wenn die Harnr\u00f6hre operiert werden muss - HEROLD.at\" \/>\n<meta property=\"og:description\" content=\"Bei einer Hypospadie m\u00fcndet die Harnr\u00f6hre an der Unterseite des Penis. Diese angeborene Entwicklungsst\u00f6rung kann durch eine Operation korrigiert werden.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.herold.at\/blog\/hypospadie-spezialisten-oesterreich\/\" \/>\n<meta property=\"og:site_name\" content=\"Herold Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/derherold\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-03T05:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-28T07:25:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2019\/04\/Hypospadie-Adobe-Stock-c-SciePro-Beitrag.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"830\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Herold Redaktion\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Herold Redaktion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.herold.at\/blog\/hypospadie-spezialisten-oesterreich\/\",\"url\":\"https:\/\/www.herold.at\/blog\/hypospadie-spezialisten-oesterreich\/\",\"name\":\"Hypospadie: Wenn die Harnr\u00f6hre operiert werden muss - HEROLD.at\",\"isPartOf\":{\"@id\":\"https:\/\/www.herold.at\/blog\/#website\"},\"datePublished\":\"2020-06-03T05:00:00+00:00\",\"dateModified\":\"2025-05-28T07:25:39+00:00\",\"author\":{\"@id\":\"https:\/\/www.herold.at\/blog\/#\/schema\/person\/12f550765e7a2ed67050cd6f459010b1\"},\"description\":\"Bei einer Hypospadie m\u00fcndet die Harnr\u00f6hre an der Unterseite des Penis. Diese angeborene Entwicklungsst\u00f6rung kann durch eine Operation korrigiert werden.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.herold.at\/blog\/hypospadie-spezialisten-oesterreich\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.herold.at\/blog\/hypospadie-spezialisten-oesterreich\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.herold.at\/blog\/hypospadie-spezialisten-oesterreich\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.herold.at\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hypospadie: Wann muss man operieren?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.herold.at\/blog\/#website\",\"url\":\"https:\/\/www.herold.at\/blog\/\",\"name\":\"Herold Blog\",\"description\":\"Ratgeber &amp; Blog von herold.at\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.herold.at\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.herold.at\/blog\/#\/schema\/person\/12f550765e7a2ed67050cd6f459010b1\",\"name\":\"Herold Redaktion\",\"url\":\"https:\/\/www.herold.at\/blog\/author\/herold-blog-team\/\"}]}<\/script>\n","yoast_head_json":{"title":"Hypospadie: Wenn die Harnr\u00f6hre operiert werden muss - HEROLD.at","description":"Bei einer Hypospadie m\u00fcndet die Harnr\u00f6hre an der Unterseite des Penis. Diese angeborene Entwicklungsst\u00f6rung kann durch eine Operation korrigiert werden.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.herold.at\/blog\/hypospadie-spezialisten-oesterreich\/","og_locale":"de_DE","og_type":"article","og_title":"Hypospadie: Wenn die Harnr\u00f6hre operiert werden muss - HEROLD.at","og_description":"Bei einer Hypospadie m\u00fcndet die Harnr\u00f6hre an der Unterseite des Penis. Diese angeborene Entwicklungsst\u00f6rung kann durch eine Operation korrigiert werden.","og_url":"https:\/\/www.herold.at\/blog\/hypospadie-spezialisten-oesterreich\/","og_site_name":"Herold Blog","article_publisher":"https:\/\/www.facebook.com\/derherold","article_published_time":"2020-06-03T05:00:00+00:00","article_modified_time":"2025-05-28T07:25:39+00:00","og_image":[{"width":830,"height":533,"url":"https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2019\/04\/Hypospadie-Adobe-Stock-c-SciePro-Beitrag.jpg","type":"image\/jpeg"}],"author":"Herold Redaktion","twitter_misc":{"Verfasst von":"Herold Redaktion","Gesch\u00e4tzte Lesezeit":"13 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.herold.at\/blog\/hypospadie-spezialisten-oesterreich\/","url":"https:\/\/www.herold.at\/blog\/hypospadie-spezialisten-oesterreich\/","name":"Hypospadie: Wenn die Harnr\u00f6hre operiert werden muss - HEROLD.at","isPartOf":{"@id":"https:\/\/www.herold.at\/blog\/#website"},"datePublished":"2020-06-03T05:00:00+00:00","dateModified":"2025-05-28T07:25:39+00:00","author":{"@id":"https:\/\/www.herold.at\/blog\/#\/schema\/person\/12f550765e7a2ed67050cd6f459010b1"},"description":"Bei einer Hypospadie m\u00fcndet die Harnr\u00f6hre an der Unterseite des Penis. Diese angeborene Entwicklungsst\u00f6rung kann durch eine Operation korrigiert werden.","breadcrumb":{"@id":"https:\/\/www.herold.at\/blog\/hypospadie-spezialisten-oesterreich\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.herold.at\/blog\/hypospadie-spezialisten-oesterreich\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.herold.at\/blog\/hypospadie-spezialisten-oesterreich\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.herold.at\/blog\/"},{"@type":"ListItem","position":2,"name":"Hypospadie: Wann muss man operieren?"}]},{"@type":"WebSite","@id":"https:\/\/www.herold.at\/blog\/#website","url":"https:\/\/www.herold.at\/blog\/","name":"Herold Blog","description":"Ratgeber &amp; Blog von herold.at","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.herold.at\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de-DE"},{"@type":"Person","@id":"https:\/\/www.herold.at\/blog\/#\/schema\/person\/12f550765e7a2ed67050cd6f459010b1","name":"Herold Redaktion","url":"https:\/\/www.herold.at\/blog\/author\/herold-blog-team\/"}]}},"fimg_url":"https:\/\/www.herold.at\/blog\/wp-content\/uploads\/2019\/04\/Hypospadie-Adobe-Stock-c-SciePro-Beitrag-560x360.jpg","_links":{"self":[{"href":"https:\/\/www.herold.at\/blog\/wp-json\/wp\/v2\/posts\/205857"}],"collection":[{"href":"https:\/\/www.herold.at\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.herold.at\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.herold.at\/blog\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/www.herold.at\/blog\/wp-json\/wp\/v2\/comments?post=205857"}],"version-history":[{"count":18,"href":"https:\/\/www.herold.at\/blog\/wp-json\/wp\/v2\/posts\/205857\/revisions"}],"predecessor-version":[{"id":256997,"href":"https:\/\/www.herold.at\/blog\/wp-json\/wp\/v2\/posts\/205857\/revisions\/256997"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.herold.at\/blog\/wp-json\/wp\/v2\/media\/210772"}],"wp:attachment":[{"href":"https:\/\/www.herold.at\/blog\/wp-json\/wp\/v2\/media?parent=205857"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.herold.at\/blog\/wp-json\/wp\/v2\/categories?post=205857"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.herold.at\/blog\/wp-json\/wp\/v2\/tags?post=205857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}